{"id":820,"date":"2015-03-24T21:21:56","date_gmt":"2015-03-24T20:21:56","guid":{"rendered":"http:\/\/staging.tv2000.it\/tg2000\/?p=820"},"modified":"2015-03-24T21:21:56","modified_gmt":"2015-03-24T20:21:56","slug":"conto-alla-rovescia-per-il-730-precompilato-che-dal-15-aprile-sara-disponibile-online","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/tg2000\/video\/conto-alla-rovescia-per-il-730-precompilato-che-dal-15-aprile-sara-disponibile-online\/","title":{"rendered":"Conto alla rovescia per il 730 precompilato che dal 15 aprile sar\u00e0 disponibile online"},"content":{"rendered":"<div class=\"fluid-embed-container\"><iframe title=\"Conto alla rovescia per il 730 precompilato che dal 15 aprile sar\u00e0 disponibile online\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/w4BKvht4Duc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>Conto alla rovescia per il 730 precompilato che dal 15 aprile sar\u00e0 disponibile on line, per dipendenti e pensionati. Il 7 luglio sar\u00e0 il termine ultimo per la consegna ma si comincia a parlare gi\u00e0 di un rinvio. Sentiamo perch\u00e9 nel servizio di Silvio Vitelli.<\/p>\n","protected":false},"featured_media":821,"comment_status":"open","ping_status":"open","template":"","tags":[],"class_list":["post-820","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-consumi","video_category-economia","video_category-news","tipologia-expost"],"acf":[],"aioseo_notices":[],"url_youtube":null,"_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=820"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/821"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=820"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}