{"id":793,"date":"2015-03-23T21:53:57","date_gmt":"2015-03-23T20:53:57","guid":{"rendered":"http:\/\/staging.tv2000.it\/tg2000\/?p=793"},"modified":"2015-03-23T21:53:57","modified_gmt":"2015-03-23T20:53:57","slug":"cei-il-card-bagnascola-corruzione-e-una-grave-offesa-ai-poveri-e-agli-onesti","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/tg2000\/video\/cei-il-card-bagnascola-corruzione-e-una-grave-offesa-ai-poveri-e-agli-onesti\/","title":{"rendered":"Cei, il card. Bagnasco:&#8221;La corruzione \u00e8 una grave offesa ai poveri e agli onesti&#8221;."},"content":{"rendered":"<div class=\"fluid-embed-container\"><iframe title=\"Cei, il card. Angelo Bagnasco:&quot;La corruzione \u00e8 una grave offesa ai poveri e agli onesti&quot;.\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/pcVIoF9xjJE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>\u201cLa corruzione \u00e8 una grave offesa ai poveri e agli onesti\u201d. A dirlo aprendo i lavori del Consiglio permanente della Conferenza Episcopale Italiana il cardinale Angelo Bagnasco, arcivescovo di Genova e Presidente della CEI. Nella prolusione del cardinale anche riflessioni sul dono del giubileo, sui cristiani perseguitati, sul tema dell\u2019 immigrazione e sulla teoria del gender. Servizio di Paolo Fucili<\/p>\n","protected":false},"featured_media":772,"comment_status":"open","ping_status":"open","template":"","tags":[],"class_list":["post-793","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-chiesa","video_category-news","tipologia-expost"],"acf":[],"aioseo_notices":[],"url_youtube":null,"_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/772"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=793"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}