{"id":548649,"date":"2025-05-29T19:01:40","date_gmt":"2025-05-29T17:01:40","guid":{"rendered":"https:\/\/staging.tv2000.it\/tg2000\/?post_type=video&#038;p=548649"},"modified":"2025-05-29T19:01:40","modified_gmt":"2025-05-29T17:01:40","slug":"femminicidi-fiaccolata-per-martina-mentre-a-torino-muore-donna-accoltellata-dal-marito","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/tg2000\/video\/femminicidi-fiaccolata-per-martina-mentre-a-torino-muore-donna-accoltellata-dal-marito\/","title":{"rendered":"Femminicidi, fiaccolata per Martina, mentre a Torino muore donna accoltellata dal marito"},"content":{"rendered":"<p>Non si arresta la lunga scia di femminicidi. Ad Afragola in migliaia partecipano alla fiaccolata per Martina, la 14enne uccisa dall\u2019ex, mentre a Torino non ce l\u2019ha fatta la donna di 61 anni accoltellata ieri dal marito. Servizi di Antonella Mitola e Barbara Masulli.<\/p>\n","protected":false},"featured_media":548651,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"class_list":["post-548649","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-cronaca","video_category-news"],"acf":[],"aioseo_notices":[],"url_youtube":"udYJyOmEatM","featured_image_url":"https:\/\/i.ytimg.com\/vi\/udYJyOmEatM\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/548649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=548649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/548651"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=548649"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=548649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}