{"id":28142,"date":"2017-09-18T20:48:55","date_gmt":"2017-09-18T18:48:55","guid":{"rendered":"http:\/\/staging.tv2000.it\/tg2000\/?post_type=video&#038;p=28142"},"modified":"2017-09-18T20:48:55","modified_gmt":"2017-09-18T18:48:55","slug":"caso-orlandi-santa-sede-smentisce-dossier-su-pagamenti-per-allontanarla-dallitalia","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/tg2000\/video\/caso-orlandi-santa-sede-smentisce-dossier-su-pagamenti-per-allontanarla-dallitalia\/","title":{"rendered":"Caso Orlandi: Santa Sede smentisce dossier su pagamenti per allontanarla dall&#8217;Italia"},"content":{"rendered":"<p>Caso Orlandi: la Santa Sede smentisce l&#8217;esistenza di un dossier sui pagamenti per allontanare dall\u2019Italia la giovane Emanuela. La ragazza, che viveva in Vaticano, era scomparsa com&#8217;\u00e8 noto nel nulla nell&#8217;estate del 1983. Servizio di Pierluigi Vito <\/p>\n","protected":false},"featured_media":28143,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"class_list":["post-28142","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-chiesa","video_category-news","video_category-vaticano"],"acf":[],"aioseo_notices":[],"url_youtube":"22BpxdwRTRU","featured_image_url":"https:\/\/i.ytimg.com\/vi\/22BpxdwRTRU\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/28142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=28142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/28143"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=28142"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=28142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}