{"id":279332,"date":"2023-10-24T13:36:36","date_gmt":"2023-10-24T11:36:36","guid":{"rendered":"https:\/\/staging.tv2000.it\/tg2000\/?post_type=video&#038;p=279332"},"modified":"2023-10-24T13:36:36","modified_gmt":"2023-10-24T11:36:36","slug":"agenzia-internazionale-energia-allarme-clima","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/tg2000\/video\/agenzia-internazionale-energia-allarme-clima\/","title":{"rendered":"Agenzia internazionale energia: allarme clima"},"content":{"rendered":"<p>Nel 2030 la quota delle rinnovabili globale salir\u00e0 al 50%, rispetto all&#8217;attuale 30% circa, e il numero di auto elettriche sar\u00e0 quasi 10 volte superiore a quello circolante nel mondo. Ma ancora non basta. \u00c8 lo scenario tratteggiato dall&#8217;Agenzia internazionale dell&#8217;energia. Il servizio di Caterina Dall\u2019Olio.<\/p>\n","protected":false},"featured_media":279333,"comment_status":"closed","ping_status":"closed","template":"","tags":[868],"class_list":["post-279332","video","type-video","status-publish","has-post-thumbnail","hentry","tag-clima","video_category-ambiente","video_category-news"],"acf":[],"aioseo_notices":[],"url_youtube":"6sbuZcOUoQM","featured_image_url":"https:\/\/i.ytimg.com\/vi\/6sbuZcOUoQM\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/279332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=279332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/279333"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=279332"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=279332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}