{"id":27727,"date":"2017-09-05T13:25:25","date_gmt":"2017-09-05T11:25:25","guid":{"rendered":"http:\/\/staging.tv2000.it\/tg2000\/?post_type=video&#038;p=27727"},"modified":"2017-09-05T13:25:43","modified_gmt":"2017-09-05T11:25:43","slug":"papa-francesco-in-colombia-mons-ortega-la-guerra-e-diventata-una-scuola-di-pace","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/tg2000\/video\/papa-francesco-in-colombia-mons-ortega-la-guerra-e-diventata-una-scuola-di-pace\/","title":{"rendered":"Papa Francesco in Colombia, Mons. Ortega: &#8220;La guerra \u00e8 diventata una scuola di pace&#8221;"},"content":{"rendered":"<p>Comincia domani il 20esimo Viaggio apostolico all&#8217;estero di Papa Francesco, che partir\u00e0 per la Colombia dove arriver\u00e0 mercoled\u00ec: &#8220;verro\u2019 come pellegrino di speranza e di pace&#8221; ha detto nel video messaggio inviato ai colombiani nel giorno in cui \u00e8 stato siglato un nuovo accordo per il cessate il fuoco tra governo e guerriglieri dell&#8217;esercito di liberazione nazionale che sara&#8217; in vigore dal 1 ottobre. &#8220;Il Papa ha seguito e incoraggiato il processo di pace&#8221;\u00a0 dice il presidente della Conferenza Episcopale Colombiana Mons. Oscar Urbina Ortega al nostro inviato Maurizio Di Schino.<\/p>\n","protected":false},"featured_media":27728,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"class_list":["post-27727","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-cinema","video_category-papa-francesco"],"acf":[],"aioseo_notices":[],"url_youtube":"ScGCT49eY4c","featured_image_url":"https:\/\/i.ytimg.com\/vi\/ScGCT49eY4c\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/27727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=27727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/27728"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=27727"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=27727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}