{"id":27451,"date":"2017-08-28T20:32:10","date_gmt":"2017-08-28T18:32:10","guid":{"rendered":"http:\/\/staging.tv2000.it\/tg2000\/?post_type=video&#038;p=27451"},"modified":"2017-08-28T20:32:25","modified_gmt":"2017-08-28T18:32:25","slug":"la-situazione-del-popolo-rohingya-al-centro-del-viaggio-di-papa-francesco-in-myanmar-e-bangladesh","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/tg2000\/video\/la-situazione-del-popolo-rohingya-al-centro-del-viaggio-di-papa-francesco-in-myanmar-e-bangladesh\/","title":{"rendered":"La situazione del popolo Rohingya al centro del Viaggio di Papa Francesco in Myanmar e Bangladesh"},"content":{"rendered":"<p>Il papa a novembre andr\u00e0 in Myanmar, un paese dove i cattolici sono solo l\u20191 per cento della popolazione. Il paese ha recentemente vissuto il passaggio dalla dittatura militare alla democrazia.\u00a0 Ma anche con il nuovo regime\u00a0 la minoranza dei Rohingya continua ad essere sottoposta ad una durissima azione repressiva. Il pontefice si recher\u00e0\u00a0 anche in Bangladesh. Servizio di Fabio Bolzetta<\/p>\n","protected":false},"featured_media":27452,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"class_list":["post-27451","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-papa-francesco"],"acf":[],"aioseo_notices":[],"url_youtube":"iK2kmgmk-CI","featured_image_url":"https:\/\/i.ytimg.com\/vi\/iK2kmgmk-CI\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/27451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=27451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/27452"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=27451"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=27451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}