{"id":27202,"date":"2017-08-21T20:05:48","date_gmt":"2017-08-21T18:05:48","guid":{"rendered":"http:\/\/staging.tv2000.it\/tg2000\/?post_type=video&#038;p=27202"},"modified":"2017-08-21T20:06:04","modified_gmt":"2017-08-21T18:06:04","slug":"barcellona-ucciso-dalla-polizia-il-killer-della-rambla","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/tg2000\/video\/barcellona-ucciso-dalla-polizia-il-killer-della-rambla\/","title":{"rendered":"Barcellona, ucciso dalla polizia il killer della Rambla"},"content":{"rendered":"<p>E&#8217; stato ucciso dalla polizia il conducente del furgone che ha falciato la folla gioved\u00ec pomeriggio sulla Rambla a Barcellona. Si tratterebbe di Younes Abouyaaqoub, che aveva indosso una cintura esplosiva. Servizio di Beatrice Bossi<\/p>\n","protected":false},"featured_media":27203,"comment_status":"closed","ping_status":"closed","template":"","tags":[1395],"class_list":["post-27202","video","type-video","status-publish","has-post-thumbnail","hentry","tag-terrorismo","video_category-attualita"],"acf":[],"aioseo_notices":[],"url_youtube":"2G9QE8SixV4","featured_image_url":"https:\/\/i.ytimg.com\/vi\/2G9QE8SixV4\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/27202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=27202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/27203"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=27202"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=27202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}