{"id":26970,"date":"2017-08-12T18:34:11","date_gmt":"2017-08-12T16:34:11","guid":{"rendered":"http:\/\/staging.tv2000.it\/tg2000\/?post_type=video&#038;p=26970"},"modified":"2017-08-14T16:16:44","modified_gmt":"2017-08-14T14:16:44","slug":"migranti-gentiloni-riceve-lappoggio-della-merkel-msf-sospende-le-attivita-davanti-alla-libia","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/tg2000\/video\/migranti-gentiloni-riceve-lappoggio-della-merkel-msf-sospende-le-attivita-davanti-alla-libia\/","title":{"rendered":"Migranti, Gentiloni riceve l&#8217;appoggio della Merkel. Msf sospende le attivit\u00e0 davanti alla Libia"},"content":{"rendered":"<p>Medici senza frontiere sospende temporaneamente l\u2019attivit\u00e0 davanti alla Libia. Lo comunica la Ong sottolineando che lo stop segue la decisione di Tripoli di istituire una propria zona di ricerca e salvataggio con limitazioni all\u2019accesso delle navi umanitarie e dopo le\u00a0 minacce ricevute dalla guardia costiera libica. Servizio di Vito D\u2019Ettorre<\/p>\n","protected":false},"featured_media":26971,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"class_list":["post-26970","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-migranti"],"acf":[],"aioseo_notices":[],"url_youtube":"x3F8AcYrD1A","featured_image_url":"https:\/\/i.ytimg.com\/vi\/x3F8AcYrD1A\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/26970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=26970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/26971"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=26970"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=26970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}