{"id":26960,"date":"2017-08-12T12:14:24","date_gmt":"2017-08-12T10:14:24","guid":{"rendered":"http:\/\/staging.tv2000.it\/tg2000\/?post_type=video&#038;p=26960"},"modified":"2017-08-14T15:50:32","modified_gmt":"2017-08-14T13:50:32","slug":"roma-atac-a-rischio-fallimento-la-situazione-del-trasporto-pubblico-in-italia","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/tg2000\/video\/roma-atac-a-rischio-fallimento-la-situazione-del-trasporto-pubblico-in-italia\/","title":{"rendered":"Roma, Atac a rischio fallimento. La situazione del trasporto pubblico in Italia"},"content":{"rendered":"<p>Agire subito oppure sar\u00e0 fallimento. Per il il Ministro delle Infrastrutture, Delrio, l\u2019Atac, l\u2019azienda municipalizzata dei trasporti nella capitale, rischia di fare la fine di Alitalia. Anzi \u2013 aggiunge &#8211;\u00a0 la mobilit\u00e0 a Roma \u00e8 forse una questione ancor pi\u00f9 seria e complessa.\u00a0 Ma qual \u00e8 la situazione trasporti nelle altre citt\u00e0, come funzionano le loro aziende municipalizzate? Servizio di Luigi Ferraiuolo<\/p>\n","protected":false},"featured_media":26961,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"class_list":["post-26960","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-cronaca"],"acf":[],"aioseo_notices":[],"url_youtube":"vV10JcK6ZXM","featured_image_url":"https:\/\/i.ytimg.com\/vi\/vV10JcK6ZXM\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/26960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=26960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/26961"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=26960"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=26960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}