{"id":26602,"date":"2017-08-03T20:42:25","date_gmt":"2017-08-03T18:42:25","guid":{"rendered":"http:\/\/staging.tv2000.it\/tg2000\/?post_type=video&#038;p=26602"},"modified":"2017-08-03T20:42:25","modified_gmt":"2017-08-03T18:42:25","slug":"il-senso-della-missione-vita-lastronauta-paolo-nespoli-spiega-lambiente-della-stazione-spaziale","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/tg2000\/video\/il-senso-della-missione-vita-lastronauta-paolo-nespoli-spiega-lambiente-della-stazione-spaziale\/","title":{"rendered":"Il senso della missione &#8220;Vita&#8221;. L&#8217;astronauta Paolo Nespoli spiega l&#8217;ambiente della Stazione Spaziale"},"content":{"rendered":"<p>Spazio: il senso della missione &#8220;Vita&#8221;. L&#8217;astronauta Paolo Nespoli spiega l&#8217;ambiente della Stazione Spaziale. Servizio di Letizia Davoli<\/p>\n","protected":false},"featured_media":26603,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"class_list":["post-26602","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-news","video_category-tecnologia"],"acf":[],"aioseo_notices":[],"url_youtube":"Jyt3hzC-Odo","featured_image_url":"https:\/\/i.ytimg.com\/vi\/Jyt3hzC-Odo\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/26602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=26602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/26603"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=26602"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=26602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}