{"id":1013,"date":"2015-03-30T20:57:53","date_gmt":"2015-03-30T18:57:53","guid":{"rendered":"http:\/\/staging.tv2000.it\/tg2000\/?p=1013"},"modified":"2015-03-30T20:57:53","modified_gmt":"2015-03-30T18:57:53","slug":"roma-al-culto-della-memoria-dei-nuovi-martiri-e-dedicata-la-basilica-di-san-bartolomeo","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/tg2000\/video\/roma-al-culto-della-memoria-dei-nuovi-martiri-e-dedicata-la-basilica-di-san-bartolomeo\/","title":{"rendered":"Roma, al culto della memoria dei nuovi martiri \u00e8 dedicata la Basilica di San Bartolomeo"},"content":{"rendered":"<div class=\"fluid-embed-container\"><iframe title=\"Ai nuovi martiri della fede \u00e8 dedicata la Basilica di San Bartolomeo nel centro di Roma\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/HgiW2EQ4_eY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>Non si fermano nel mondo le persecuzioni contro i cristiani. Costretti alla fuga, privati della libert\u00e0 o uccisi a causa della propria fede. Domani &#8211; come ogni anno all\u2019inizio della Settimana Santa &#8211; la comunit\u00e0 di Sant\u2019Egidio promuove un incontro di preghiera ecumenica. Al culto della memoria dei nuovi martiri per la fede si dedica in particolare la Basilica di San Bartolomeo nel centro di Roma. Scopriamo perch\u00e9 con Francesco Durante<\/p>\n","protected":false},"featured_media":1014,"comment_status":"open","ping_status":"open","template":"","tags":[],"class_list":["post-1013","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-chiesa","video_category-news","tipologia-expost"],"acf":[],"aioseo_notices":[],"url_youtube":null,"_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video\/1013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/comments?post=1013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media\/1014"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/media?parent=1013"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/tg2000\/wp-json\/wp\/v2\/tags?post=1013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}