{"id":7366,"date":"2016-10-17T15:12:39","date_gmt":"2016-10-17T13:12:39","guid":{"rendered":"http:\/\/staging.tv2000.it\/siamonoi\/?p=7366"},"modified":"2016-10-19T01:51:26","modified_gmt":"2016-10-18T23:51:26","slug":"renzo-arbore-a-siamo-noi-un-viaggio-nellincredibile-storia-della-radio","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/siamonoi\/2016\/10\/17\/renzo-arbore-a-siamo-noi-un-viaggio-nellincredibile-storia-della-radio\/","title":{"rendered":"Renzo Arbore a Siamo Noi: un viaggio nell&#8217;incredibile storia della radio"},"content":{"rendered":"<p><strong>Marted\u00ec 18 ottobre,<\/strong> un viaggio in compagnia di un ospite molto speciale: il grande <strong>Renzo Arbore <\/strong>che ci porter\u00e0 alla scoperta, anzi alla riscoperta della radio.<\/p>\n<p><strong>Memoria storica, curiosit\u00e0 e tanti aneddoti<\/strong> per celebrare i 96 anni dalla prima trasmissione radiofonica in Italia: era il 1924 e la voce era quella di Maria Luisa Boncompagni.<\/p>\n<p><strong>Nel corso della puntata<\/strong> si parler\u00e0 anche di agricoltura biologica: un metodo di produzione nel rispetto totale dell\u2019ambiente con <strong>Vincenzo Vizioli<\/strong>, presidente dell\u2019 AIAB, Associazione Italiana per l\u2019agricoltura Biologica, <strong>Bruno Sebastianelli<\/strong>, \u00a0presidente della cooperativa agricola biologica \u201cLa terra e il cielo\u201d e <strong>Lionello Righetti<\/strong>, titolare dell\u2019azienda agricola biologica \u201cL\u2019albero che cammina\u201d.<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"Siamo noi - Puntata del 18 ottobre\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/J7wARcPBfHQ?list=PL6AqvbxnE8H4uB6OW69hCWEUkN8uHJQhu\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"Marted\u00ec 18 ottobre, un viaggio in compagnia di un ospite molto speciale: il grande Renzo Arbore che ci porter\u00e0 alla scoperta, anzi alla riscoperta della radio. Memoria storica, curiosit\u00e0 e tanti aneddoti per celebrare i 96 anni dalla prima trasmissione radiofonica in Italia: era il 1924 e la voce era quella di Maria Luisa Boncompagni. [&hellip;]","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[51,169,167,168,166,164,163,165,71],"class_list":["post-7366","post","type-post","status-publish","format-standard","hentry","category-senza-categoria","tag-agricoltura","tag-agricoltura-biologica","tag-arbore","tag-bio","tag-musica","tag-radio","tag-renzo-arbore","tag-storia","tag-tv2000"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/posts\/7366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/comments?post=7366"}],"version-history":[{"count":6,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/posts\/7366\/revisions"}],"predecessor-version":[{"id":7369,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/posts\/7366\/revisions\/7369"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/media?parent=7366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/categories?post=7366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/tags?post=7366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}