{"id":13325,"date":"2018-05-11T10:17:36","date_gmt":"2018-05-11T08:17:36","guid":{"rendered":"http:\/\/staging.tv2000.it\/siamonoi\/?p=13325"},"modified":"2018-05-11T10:17:36","modified_gmt":"2018-05-11T08:17:36","slug":"la-mamma-di-emanuele-e-la-visita-del-papa-adesso-mio-figlio-e-piu-sereno","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/siamonoi\/2018\/05\/11\/la-mamma-di-emanuele-e-la-visita-del-papa-adesso-mio-figlio-e-piu-sereno\/","title":{"rendered":"La mamma di Emanuele e la visita del Papa <br> &#8220;Adesso mio figlio \u00e8 pi\u00f9 sereno&#8221;"},"content":{"rendered":"<p>La storia che oggi affrontiamo nel nostro &#8220;tutorial&#8221; dei sentimenti riguarda i dubbi di Michela, una nostra telespettatrice. Ha 30 anni ed ha ricevuto una proposta di matrimonio. Ma non sa se accettare. Il motivo? L&#8217;invadenza della famiglia del fidanzato che considera insopportabile. Ne parliamo oggi, dalle 13.50, con\u00a0<strong>Antonio Fatigati, <\/strong>teologo, diacono permanente della diocesi di Milano, che svolge la sua attivit\u00e0 di esperto in tematiche familiari presso la comunit\u00e0 pastorale San Francesco d\u2019Assisi in Monza.<\/p>\n<p>Subito dopo sar\u00e0 con noi in studio <strong>Elisabetta Pacciotti De Felici<\/strong>, la mamma del piccolo Emanuele.<\/p>\n<p>Emanuele \u00e8 il bambino che domenica 15 aprile durante la visita di Papa Francesco\u00a0alla parrocchia di San Paolo della Croce a Corviale ha chiesto, fra le lacrime, a Papa Bergoglio di sapere dove fosse il padre: morto da qualche tempo, il padre &#8211; ha spiegato Emanuele al Pontefice &#8211; era non credente. Papa Francesco lo ha rassicurato. ti segue, orgoglioso, dal cielo.<\/p>\n<p>Nello spazio religioso, continua il nostro viaggio nella devozione mariana nel mese di maggio, tradizionalmente dedicato alla Madonna.\u00a0Dopo aver parlato della Madonna di Pompei, oggi approfondiremo il culto della Madonna di Fatima. Domenica prossima,\u00a0 13 maggio si celebrano infatti le apparizioni della Vergine Maria a Fatima, avvenute nel 1917. In studio <strong>padre Mario Piatti\u00a0<\/strong>della Congregazione Servi del Cuore Immacolato di Maria e direttore della Rivista \u201cMaria Di Fatima\u201d\u00a0e la devota<strong> Marilda Zonarelli.<\/strong><\/p>\n<p>Alle 15.20 ci metteremo in viaggio verso Lucca dove oggi si apre l&#8217;ottava edizione del Festival del volontariato. Il nostro inviato Vito D&#8217;Ettorre sar\u00e0 con <strong>Edoardo Patriarca<\/strong>, presidente del Centro nazionale per il volontariato e con due incredibili volontari del Cai, il centro Alpino italiano, <strong>Aldo Terreni<\/strong> e <strong>Giuseppe Comuniello<\/strong>.<\/p>\n<p>In studio invece l&#8217;attore<strong> Jonis Bashir<\/strong>, attentissimo e attivo sui temi dei diritti sociali, <strong>Giulio De Rita<\/strong>, ricercatore del Censis e le volontarie <strong>Laura Casaldi<\/strong> del Moige e <strong>Anna Marchei<\/strong> della comunit\u00e0 di Sant&#8217;Egidio.<\/p>\n","protected":false},"excerpt":{"rendered":"La storia che oggi affrontiamo nel nostro &#8220;tutorial&#8221; dei sentimenti riguarda i dubbi di Michela, una nostra telespettatrice. Ha 30 anni ed ha ricevuto una proposta di matrimonio. Ma non sa se accettare. Il motivo? L&#8217;invadenza della famiglia del fidanzato che considera insopportabile. Ne parliamo oggi, dalle 13.50, con\u00a0Antonio Fatigati, teologo, diacono permanente della diocesi [&hellip;]","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[1460,1465,513,1053,1459,1456,1463,1461,1462,1464,428,1458,1457],"class_list":["post-13325","post","type-post","status-publish","format-standard","hentry","category-senza-categoria","tag-aldo-terreni","tag-anna-marchei","tag-antonio-fatigati","tag-comunita-di-santegidio","tag-edoardo-patriarca","tag-elisabetta-pacciotti-de-felici","tag-giulio-de-rita","tag-giuseppe-comuniello","tag-jonis-bashir","tag-laura-casaldi","tag-madonna-di-fatima","tag-marilda-zonarelli","tag-padre-mario-piatti"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/posts\/13325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/comments?post=13325"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/posts\/13325\/revisions"}],"predecessor-version":[{"id":13326,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/posts\/13325\/revisions\/13326"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/media?parent=13325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/categories?post=13325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/tags?post=13325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}