{"id":12468,"date":"2018-02-27T10:25:19","date_gmt":"2018-02-27T09:25:19","guid":{"rendered":"http:\/\/staging.tv2000.it\/siamonoi\/?p=12468"},"modified":"2018-02-28T08:34:18","modified_gmt":"2018-02-28T07:34:18","slug":"il-gelo-di-burian-colpisce-litalia-cosa-succedera-nei-prossimi-giorni","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/siamonoi\/2018\/02\/27\/il-gelo-di-burian-colpisce-litalia-cosa-succedera-nei-prossimi-giorni\/","title":{"rendered":"Il gelo di Burian colpisce l&#8217;Italia <br> Cosa succeder\u00e0 nei prossimi giorni?"},"content":{"rendered":"<div class=\"fluid-embed-container\"><iframe title=\"Siamo Noi - Puntata del 27 febbraio 2018\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/wB_-XlVan68?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>Italia nel gelo: scuole chiuse a Roma e un freddo che dal Nord, potenzialmente pi\u00f9 preparato ad affrontare\u00a0le situazioni di emergenza, si sposta sempre pi\u00f9 a sud. Oggi a Siamo Noi, dalle 13.50, ne parliamo con\u00a0la collega, collaboratrice de\u00a0la Stampa, <strong>Antonella Rampino<\/strong> con cui\u00a0leggeremo e commenteremo\u00a0le notizie pi\u00f9 importanti della giornata.<\/p>\n<p>Il freddo sar\u00e0 anche\u00a0l&#8217;argomento di un altro approfondimento del programma, quando alle 15.20 ci occuperemo di cambiamenti climatici con <strong>Simonetta Lombardo<\/strong>, giornalista ed esperta di temi ambientali, con\u00a0l&#8217;urbanista\u00a0<strong>Sandro Simoncini<\/strong>,\u00a0<strong>Andrea Minutolo<\/strong>, coordinatore dell\u2019Ufficio scientifico di Legambiente,\u00a0<strong>Cristian Pacini<\/strong>, capitano del servizio Meteorologico Aeronautica Militare. Con noi anche un ospite che ci aiuter\u00e0 a prendere con\u00a0leggerezza\u00a0le difficolt\u00e0 di questi momenti:\u00a0<strong>Andy Luotto<\/strong>\u00a0che ci dar\u00e0 consigli su come affrontare il grande freddo nel suo\u00a0luogo preferito della casa, la cucina.<\/p>\n<p>La programmazione di Siamo Noi, prevede comunque altri importanti protagonisti: al divanetto intervistato da Massimiliano Niccoli oggi arriva <strong>Marco Presta<\/strong>, storico conduttore del Ruggito del Coniglio su Radio2. Ha appena pubblicato per Einaudi &#8220;Accendimi&#8221;.\u00a0Ci racconter\u00e0 il suo lavoro, gli sketch e approfondiremo il ruolo dell\u2019educatore e di come la parola (scritta o parlata in radio) possa accendere l\u2019immaginazione e i cuori delle persone.<\/p>\n<p>Nello spazio religioso oggi approfondiremo\u00a0la &#8220;Preghiera di&#8230;&#8221;\u00a0San Bernardo di Chiaravalle. In studio a parlarcene saranno \u00a0<strong>Padre Alberto Coratti, <\/strong>monaco cistercense, responsabile della biblioteca interna all\u2019abbazia cistercense di Casamari a Veroli in provincia di Frosinone e<strong>\u00a0Massimo Maria Civale, <\/strong>Vicario Confederazione Internazionale Templare \u201cSan Bernardo di Chiaravalle\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"Italia nel gelo: scuole chiuse a Roma e un freddo che dal Nord, potenzialmente pi\u00f9 preparato ad affrontare\u00a0le situazioni di emergenza, si sposta sempre pi\u00f9 a sud. Oggi a Siamo Noi, dalle 13.50, ne parliamo con\u00a0la collega, collaboratrice de\u00a0la Stampa, Antonella Rampino con cui\u00a0leggeremo e commenteremo\u00a0le notizie pi\u00f9 importanti della giornata. Il freddo sar\u00e0 anche\u00a0l&#8217;argomento [&hellip;]","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[1158,1091,1155,720,1159,1163,1162,1161,1157,1156],"class_list":["post-12468","post","type-post","status-publish","format-standard","hentry","category-senza-categoria","tag-andrea-minutolo","tag-andy-luotto","tag-antonella-rampino","tag-cristian-pacini","tag-marco-presta","tag-massimo-maria-civale","tag-padre-alberto-coratti","tag-san-bernardo-di-chiaravalle","tag-sandro-simoncini","tag-simonetta-lombardo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/posts\/12468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/comments?post=12468"}],"version-history":[{"count":4,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/posts\/12468\/revisions"}],"predecessor-version":[{"id":12488,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/posts\/12468\/revisions\/12488"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/media?parent=12468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/categories?post=12468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/tags?post=12468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}