{"id":10668,"date":"2017-10-04T18:06:27","date_gmt":"2017-10-04T16:06:27","guid":{"rendered":"http:\/\/staging.tv2000.it\/siamonoi\/?p=10668"},"modified":"2017-10-06T09:27:04","modified_gmt":"2017-10-06T07:27:04","slug":"dalle-liti-condominiali-alle-passioni-e-hobby-tutti-gli-ospiti-di-siamo-noi-domani-dalle-13-50","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/siamonoi\/2017\/10\/04\/dalle-liti-condominiali-alle-passioni-e-hobby-tutti-gli-ospiti-di-siamo-noi-domani-dalle-13-50\/","title":{"rendered":"Dalle liti condominiali alle passioni e hobby <br> Tutti gli ospiti di Siamo Noi. Rivedi la puntata"},"content":{"rendered":"<div class=\"fluid-embed-container\"><iframe title=\"Siamo Noi - puntata del 5 ottobre 2017\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/ed133yYUnwU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>La riunione di condominio si avvicina inesorabilmente? Avete da discutere con il vicino del piano superiore perch\u00e9 dal suo balcone continua a scorrere quell&#8217;acqua che macchia il vostro bucato? Non tutti fanno la raccolta differenziata e i costi pesano su tutti? Che fatica vivere in condominio.<\/p>\n<p>Lo sa bene l&#8217;avvocato <strong>Barbara Fiorentino<\/strong> che\u00a0oggi a Siamo Noi aprir\u00e0 lo spazio dei &#8220;tutorial&#8221; cercando di districare le pi\u00f9 comuni liti condominiali. Se avete dubbi o domande da porre ai nostri esperti\u00a0<b>\u00a0<\/b>i nostri contatti sono aperti: scrivete\u00a0una mail a\u00a0<a href=\"mailto:siamonoi@tv2000.it\" target=\"_blank\" rel=\"noopener noreferrer\">siamonoi@tv2000.it<\/a>\u00a0o una lettera a Siamo Noi\/Tv2000,\u00a0<a href=\"https:\/\/maps.google.com\/?q=Via+Aurelia+796+-+00165+Roma&amp;entry=gmail&amp;source=g\">Via Aurelia 796 \u2013 00165 Roma<\/a>.<\/p>\n<p>Nell&#8217;intervista della riconoscenza il protagonista ci inviter\u00e0 a non lamentarci mai.\u00a0Lui \u00e8\u00a0<strong>Salvo No\u00e8<\/strong> ed \u00e8 lo psicologo e psicoterapeuta che il 14 giugno di quest\u2019anno ha donato a Papa Francesco il decalogo delle ragioni per le quali \u00e8 \u201cvietato lamentarsi\u201d. Un dono molto apprezzato dal Pontefice che ha affisso il cartello sulla porta del suo ufficio a Santa Marta.<\/p>\n<p>A seguire il primo appuntamento con \u201cla preghiera di\u2026\u201d:\u00a0<strong>Padre Bruno Epinat<\/strong>\u00a0guider\u00e0 i telespettatori alla scoperta di una preghiera sull\u2019umilt\u00e0 scritta da Santa Teresina di Lisieux.<\/p>\n<p>Dalle 15.20, Siamo Noi invece vuole proporvi una carrellata di grandi passioni: per il gioco (con un gruppo di giocatori di bocce), per le bambole con un collezionista, per la bici con la testimonianza di <strong>Don Donato Agostinelli<\/strong>. E poi racconteremo una passione tutta particolare: quella degli anziani che controllano i lavori nei cantieri edili.<\/p>\n<p>Se non lo sapete si chiamano Umarells: collegamento da Bologna nella piazza che il comune intitoler\u00e0 proprio agli Umarells.<\/p>\n","protected":false},"excerpt":{"rendered":"La riunione di condominio si avvicina inesorabilmente? Avete da discutere con il vicino del piano superiore perch\u00e9 dal suo balcone continua a scorrere quell&#8217;acqua che macchia il vostro bucato? Non tutti fanno la raccolta differenziata e i costi pesano su tutti? Che fatica vivere in condominio. Lo sa bene l&#8217;avvocato Barbara Fiorentino che\u00a0oggi a Siamo [&hellip;]","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[505,504,501],"tags":[510,509,507,511,508,506],"class_list":["post-10668","post","type-post","status-publish","format-standard","hentry","category-attualita","category-spiritualita-e-fede","category-tutorial","tag-barbara-fiorentino","tag-liti-condominiali","tag-padre-bruno-epinat","tag-salvo-noe","tag-santa-teresina-di-lisieux","tag-umarells"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/posts\/10668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/comments?post=10668"}],"version-history":[{"count":3,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/posts\/10668\/revisions"}],"predecessor-version":[{"id":10700,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/posts\/10668\/revisions\/10700"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/media?parent=10668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/categories?post=10668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/siamonoi\/wp-json\/wp\/v2\/tags?post=10668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}