{"id":386,"date":"2024-11-06T12:26:58","date_gmt":"2024-11-06T11:26:58","guid":{"rendered":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/?post_type=video&#038;p=386"},"modified":"2024-11-06T12:26:58","modified_gmt":"2024-11-06T11:26:58","slug":"torta-degli-addobbi","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/video\/torta-degli-addobbi\/","title":{"rendered":"Torta degli addobbi"},"content":{"rendered":"<p>TORTA DEGLI ADDOBBI<br \/>\n1 LT LATTE INTERO<br \/>\n200 GR RISO CARNAROLI (O ARBORIO)<br \/>\n100 GR MANDORLE TRITATE<br \/>\n4 UOVA<br \/>\n200 GR ZUCCHERO SEMOLATO<br \/>\n1 BACCA VANIGLIA<br \/>\nSCORZA DI UN LIMONE<\/p>\n<p>Per preparare la torta degli addobbi abbiamo messo il latte in un tegame con la bacca di vaniglia e la scorza del limone. Abbiamo portato a bollore, versato il riso e fatto cuocere finch\u00e9 il riso non si sar\u00e0 asciugato abbastanza, ma lasciandolo un po\u2019 al dente. Abbiamo fatto raffreddare completamente, eliminato la bacca di vaniglia e la scorza del limone (se vi piace, potete anche lasciarla nella torta tagliata finemente), e poi abbiamo aggiunto le mandorle tritate grossolanamente, lo zucchero e le uova. Abbiamo amalgamato con cura e versato in una tortiera da 24 cm rivestita di staccante. Abbiamo cotto in forno preriscaldato a 170\u00b0 per circa 50\/60 minuti.<br \/>\nAbbiamo sfornato e lasciato raffreddare. Poi abbiamo servito bagnando la superficie con qualche pennellata di liquore Sassolino.<\/p>\n","protected":false},"featured_media":387,"comment_status":"open","ping_status":"closed","template":"","tags":[],"class_list":["post-386","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-ricette-dolci"],"acf":[],"aioseo_notices":[],"url_youtube":"q8cY-cVHNn8","featured_image_url":"https:\/\/i.ytimg.com\/vi\/q8cY-cVHNn8\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/video\/386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/comments?post=386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media\/387"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media?parent=386"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/tags?post=386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}