{"id":336,"date":"2024-10-23T12:01:24","date_gmt":"2024-10-23T10:01:24","guid":{"rendered":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/?post_type=video&#038;p=336"},"modified":"2024-10-23T12:01:24","modified_gmt":"2024-10-23T10:01:24","slug":"gnocchi-allo-zafferano-e-gorgonzola","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/video\/gnocchi-allo-zafferano-e-gorgonzola\/","title":{"rendered":"Gnocchi allo zafferano e gorgonzola"},"content":{"rendered":"<p>LA RICETTA DI FABIO: GNOCCHI ALLO ZAFFERANO E GORGONZOLA<\/p>\n<p>PER 900 GR DI GNOCCHI:<br \/>\n500 GR PATATE BOLLITE E SCHIACCIATE<br \/>\n300 GR FARINA<br \/>\n1 TUORLO<br \/>\n300 GR GORGONZOLA<br \/>\n3 BUSTINE ZAFFERANO<br \/>\n200 ML PANNA DA CUCINA FRESCA<br \/>\n50GR GRANA GRATTUGIATO<\/p>\n<p>Per preparare gli gnocchi allo zafferano e gorgonzola con riduzione di ginepro abbiamo impastato gli gnocchi mettendo su di una spianatoia la farina con le patate bollite e schiacciate e le uova. Abbiamo lavorato l\u2019impasto fino a che non \u00e8 stato omogeneo e poi abbiamo ricavato degli gnocchi grandi quanto una nocciola.<br \/>\nPoi abbiamo fatto la riduzione facendo bollire in acqua le bacche di ginepro. Abbiamo frullato e filtrato il composto, lo abbiamo addensato con amido di mais e messo in un dosatore.<br \/>\nIn un altro pentolino abbiamo sciolto il gorgonzola nella crema di latte, abbiamo aggiunto lo zafferano e lasciato addensare.<br \/>\nAbbiamo sbollentato gli gnocchi e li abbiamo amalgamati alla crema di gorgonzola e zafferano. Abbiamo impiattato finendo con granella di noci e la riduzione di ginepro.<\/p>\n","protected":false},"featured_media":337,"comment_status":"open","ping_status":"closed","template":"","tags":[],"class_list":["post-336","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-ricette-primi"],"acf":[],"aioseo_notices":[],"url_youtube":"GirZOkbDf3c","featured_image_url":"https:\/\/i.ytimg.com\/vi\/GirZOkbDf3c\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/video\/336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/comments?post=336"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media\/337"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media?parent=336"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/tags?post=336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}