{"id":2659,"date":"2025-03-03T12:34:09","date_gmt":"2025-03-03T11:34:09","guid":{"rendered":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/?post_type=video&#038;p=2659"},"modified":"2025-03-03T12:34:09","modified_gmt":"2025-03-03T11:34:09","slug":"millefoglie-di-tozzetti-alle-mandorle-con-riduzione-di-mosto-cotto","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/video\/millefoglie-di-tozzetti-alle-mandorle-con-riduzione-di-mosto-cotto\/","title":{"rendered":"Millefoglie di tozzetti alle mandorle con riduzione di mosto cotto"},"content":{"rendered":"<p>Quel che bolle in pentola (TV2000) &#8211; Millefoglie di tozzetti alle mandorle con riduzione di mosto cotto &#8211; 3 marzo 2025<\/p>\n","protected":false},"featured_media":2660,"comment_status":"open","ping_status":"closed","template":"","tags":[],"class_list":["post-2659","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-ricette-dolci"],"acf":[],"aioseo_notices":[],"url_youtube":"uVcp6EE4wBQ","featured_image_url":"https:\/\/i.ytimg.com\/vi\/uVcp6EE4wBQ\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/video\/2659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/comments?post=2659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media\/2660"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media?parent=2659"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/tags?post=2659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}