{"id":246,"date":"2024-10-14T12:16:18","date_gmt":"2024-10-14T10:16:18","guid":{"rendered":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/?post_type=video&#038;p=246"},"modified":"2024-10-14T15:35:08","modified_gmt":"2024-10-14T13:35:08","slug":"zuppa-di-pane-con-funghi-porcini","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/video\/zuppa-di-pane-con-funghi-porcini\/","title":{"rendered":"Zuppa di pane con funghi porcini"},"content":{"rendered":"<p>Quel che bolle in pentola (TV2000) &#8211; Zuppa di pane con funghi porcini &#8211; 14 ottobre 2024<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>ZUPPA DI PANE CON FUNGHI PORCINI (O MISTO FUNGHI)<\/strong><\/li>\n<\/ul>\n<p>250 GR PANE RAFFERMO<\/p>\n<p>1 L BRODO VEGETALE<\/p>\n<p>BACCHE DI GINEPRO E FOGLIE D\u2019ALLORO<\/p>\n<p>100 GR PORCINI SECCHI (O MISTI)<\/p>\n<p>OLIO EXTRA VERGINE D\u2019OLIVA<\/p>\n<p>AGLIO<\/p>\n<p>PREZZEMOLO<\/p>\n<p>SALE&nbsp;&nbsp;<\/p>\n<p>1 PEPERONCINO O OLIO PICCANTE<\/p>\n<p>PARMIGIANO GRATTUGIATO<\/p>\n<p>&nbsp;<\/p>\n<p>Per preparare la zuppa di porcini secchi abbiamo messo in ammollo i funghi in acqua calda per almeno un\u2019oretta.<\/p>\n<p>Li abbiamo strizzati bene tenendo da parte l\u2019acqua dell\u2019ammollo per utilizzarla durante la cottura.<\/p>\n<p>Nella padella antiaderente abbiamo riscaldato l\u2019olio con l\u2019aglio e ci abbiamo versato i funghi, abbiamo lasciato insaporire per 5 minuti, aggiungendo il prezzemolo.&nbsp; Poi abbiamo lasciato cuocere per 20\/30 minuti circa, aggiungendo l\u2019acqua filtrata dei funghi.<\/p>\n<p>Abbiamo messo in ammollo il pane con l\u2019alloro e le bacche di ginepro nel brodo vegetale. Quando il pane \u00e8 stato ben morbido lo abbiamo aggiunto in padella e lasciato cuocere insieme ai funghi per altri 10 minuti. Abbiamo completato con il peperoncino e con una spolverata di formaggio parmigiano e giro di olio piccante.<\/p>\n","protected":false},"featured_media":247,"comment_status":"open","ping_status":"closed","template":"","tags":[],"class_list":["post-246","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-ricette-primi"],"acf":[],"aioseo_notices":[],"url_youtube":"gMpeIN_McXo","featured_image_url":"https:\/\/i.ytimg.com\/vi\/gMpeIN_McXo\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/video\/246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/comments?post=246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media\/247"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media?parent=246"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/tags?post=246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}