{"id":211,"date":"2024-10-09T12:26:11","date_gmt":"2024-10-09T10:26:11","guid":{"rendered":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/?post_type=video&#038;p=211"},"modified":"2024-10-09T12:26:11","modified_gmt":"2024-10-09T10:26:11","slug":"capresine","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/video\/capresine\/","title":{"rendered":"Capresine"},"content":{"rendered":"<p>CAPRESINE<\/p>\n<p>DOSI PER 10 PEZZI:<br \/>\n165 GR BURRO<br \/>\n37 GR OLIO DI SEMI GIRASOLE<br \/>\n155 GR FARINA DI MANDORLE<br \/>\n150 GR ZUCCHERO A VELO<br \/>\n150 GR ZUCCHERO SEMOLATO<br \/>\n92 ML ACQUA<br \/>\n250 GR CIRCA 5 UOVA MEDIE<br \/>\n75 GR CACAO AMARO<br \/>\n10 GR LIEVITO IN POLVERE<br \/>\n202 GR FECOLA<br \/>\n1 ARANCIA<br \/>\n20 GR MANDORLE PELATE<\/p>\n<p>Per preparare le capresine abbiamo messo in una ciotola la farina di mandorle, lo zucchero a velo, il cacao, il lievito, la fecola, lo zucchero semolato, la scorza dell\u2019arancia, l\u2019acqua, le uova lavorate con le fruste insieme all\u2019olio e al burro. Abbiamo amalgamato bene e messo a lievitare per poco tempo accanto a una fonte di calore. Abbiamo messo nei pirottini prima una mandorla intera e poi il composto della torta, avendo cura di lasciarlo basso per dargli la possibilit\u00e0 di crescere in forno. Abbiamo disposto in superficie delle mandorle sminuzzate e messo in forno ventilato e gi\u00e0 riscaldato a 160 gradi per circa 20 minuti.<\/p>\n","protected":false},"featured_media":212,"comment_status":"open","ping_status":"closed","template":"","tags":[],"class_list":["post-211","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-ricette-dolci"],"acf":[],"aioseo_notices":[],"url_youtube":"mocpAkaUcJM","featured_image_url":"https:\/\/i.ytimg.com\/vi\/mocpAkaUcJM\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/video\/211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/comments?post=211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media\/212"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media?parent=211"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/tags?post=211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}