{"id":3323,"date":"2025-03-20T13:35:09","date_gmt":"2025-03-20T12:35:09","guid":{"rendered":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/?p=3323"},"modified":"2025-03-20T13:35:09","modified_gmt":"2025-03-20T12:35:09","slug":"zucchine-ripiene-di-carne-e-ricotta-cheesecake-menta-e-cioccolato","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/2025\/03\/20\/zucchine-ripiene-di-carne-e-ricotta-cheesecake-menta-e-cioccolato\/","title":{"rendered":"Zucchine ripiene di carne e ricotta, cheesecake menta e cioccolato"},"content":{"rendered":"<div class=\"rwd-video\"><iframe title=\"Play 2000\" src=\"https:\/\/www.play2000.it\/play\/episode\/15275?startAt=0&#038;backToUrl=%2Fdetail%2F331%3Fepisode_id%3D15275%26season_id%3D385\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/div>\n<p>Nella cucina di &#8220;Quel che bolle in pentola&#8221;, lo chef Fabio prepara le zucchine con pomodorini, ripiene di carne e ricotta. Nel frattempo, la nostra ospite Claudia, accompagnata dalla sua amica Daniela, cucina per gli assaggiatori una cheesecake menta e cioccolato, e lo scarpasot tipico di Correggio.<\/p>\n","protected":false},"excerpt":{"rendered":"\ufeff Nella cucina di &#8220;Quel che bolle in pentola&#8221;, lo chef Fabio prepara le zucchine con pomodorini, ripiene di carne e ricotta. Nel frattempo, la nostra ospite Claudia, accompagnata dalla sua amica Daniela, cucina per gli assaggiatori una cheesecake menta e cioccolato, e lo scarpasot tipico di Correggio.","protected":false},"author":6,"featured_media":3324,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puntate-2024-2025"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-content\/uploads\/sites\/79\/2025\/03\/pentolaquad-4.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/posts\/3323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/comments?post=3323"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/posts\/3323\/revisions"}],"predecessor-version":[{"id":3325,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/posts\/3323\/revisions\/3325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media\/3324"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media?parent=3323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/categories?post=3323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/tags?post=3323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}