{"id":2894,"date":"2025-03-11T14:40:45","date_gmt":"2025-03-11T13:40:45","guid":{"rendered":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/?p=2894"},"modified":"2025-03-11T14:40:45","modified_gmt":"2025-03-11T13:40:45","slug":"trofie-con-gamberi-e-friggitelli-crostata-con-marmellata-di-arance-torta-girella","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/2025\/03\/11\/trofie-con-gamberi-e-friggitelli-crostata-con-marmellata-di-arance-torta-girella\/","title":{"rendered":"Trofie con gamberi e friggitelli, crostata con marmellata di arance, torta girella"},"content":{"rendered":"<div class=\"rwd-video\"><iframe title=\"Play 2000\" src=\"https:\/\/www.play2000.it\/play\/episode\/14833?startAt=0&#038;backToUrl=%2Fdetail%2F331%3Fepisode_id%3D14833%26season_id%3D385\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/div>\n<p>Riapre la cucina di Quel che bolle in pentola: oggi il nostro chef Fabio Cinelli, ha preparato le trofie con gamberi e friggitelli. La signora Roberta invece, ospite marchigiana di questa puntata, ha preparato per gli assaggiatori una crostata integrale all&#8217;olio con marmellata di arance e la torta girella<\/p>\n","protected":false},"excerpt":{"rendered":"\ufeff Riapre la cucina di Quel che bolle in pentola: oggi il nostro chef Fabio Cinelli, ha preparato le trofie con gamberi e friggitelli. La signora Roberta invece, ospite marchigiana di questa puntata, ha preparato per gli assaggiatori una crostata integrale all&#8217;olio con marmellata di arance e la torta girella","protected":false},"author":6,"featured_media":2895,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puntate-2024-2025"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-content\/uploads\/sites\/79\/2025\/03\/pentolaquad-2.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/posts\/2894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/comments?post=2894"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/posts\/2894\/revisions"}],"predecessor-version":[{"id":2896,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/posts\/2894\/revisions\/2896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media\/2895"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media?parent=2894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/categories?post=2894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/tags?post=2894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}