{"id":277,"date":"2024-10-16T14:59:12","date_gmt":"2024-10-16T12:59:12","guid":{"rendered":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/?p=277"},"modified":"2024-10-16T14:59:13","modified_gmt":"2024-10-16T12:59:13","slug":"16-ottobre-2024","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/2024\/10\/16\/16-ottobre-2024\/","title":{"rendered":"16 ottobre 2024"},"content":{"rendered":"<div class=\"rwd-video\"><iframe title=\"Play 2000\" src=\"https:\/\/www.play2000.it\/play\/episode\/8607?startAt=0&#038;backToUrl=%2Fdetail%2F331\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/div>\n<p>1)\tLA RICETTA DI FABIO: FINOCCHI GRATINATI CON POMODORINI, CIPOLLA E OLIVE<br \/>\n1 FINOCCHIO<br \/>\n1 CIPOLLA<br \/>\n300 GR POMODORINI<br \/>\n60 GR OLIO EXTRA VERGINE D\u2019OLIVA<br \/>\n60 GR PANGRATTATO<br \/>\n50 GR PARMIGIANO<br \/>\n40 GR OLIVE NERE DENOCCIOLATE<br \/>\n1 CIUFFO PREZZEMOLO<br \/>\n1 SPICCHIO D\u2019AGLIO<br \/>\nSALE E PEPE<\/p>\n<p>Per preparare i finocchi gratinati abbiamo pulito il finocchio e lo abbiamo affettato sottilmente. Lo abbiamo messo in una ciotola insieme ai pomodorini tagliati a met\u00e0 e alla cipolla.<br \/>\nAbbiamo condito con olio, sale, pepe, pangrattato, abbondante prezzemolo tritato finemente, aglio e parmigiano grattugiato. Abbiamo aggiunto un goccio d\u2019acqua e amalgamato per bene. Infine abbiamo aggiunto le olive intere.<br \/>\nAbbiamo quindi disposto i nostri finocchi in teglia rivestita di carta forno e cotto a 200\u00b0 in modalit\u00e0 ventilata per circa 20 minuti, fino a che non si \u00e8 formata una crosticina sopra.<\/p>\n<p>2)\tPASTICCIO DI MACCHERONI ALLA FERRARESE<br \/>\nPER LA PASTA FROLLA:<br \/>\n500 GR FARINA 00<br \/>\n230 GR BURRO<br \/>\n150 GR ZUCCHERO<br \/>\n5 TUORLI<br \/>\n1 LIMONE<br \/>\nSALE<br \/>\nPER IL SUGO:<br \/>\n150 GR MACINATO DI VITELLO<br \/>\n150 GR MACINATO MISTO<br \/>\n5 SALSICCE<br \/>\n1 COSTA SEDANO<br \/>\n1 CAROTA<br \/>\n1 CIPOLLA<br \/>\nOLIO EXTRA VERGINE D\u2019OLIVA<br \/>\nSALE<br \/>\nPER IL RIPIENO:<br \/>\n35 GR FUNGHI SECCHI<br \/>\n70 GR PARMIGIANO REGGIANO<br \/>\n300 GR MACCHERONCINI RIGATI<br \/>\nPER LA BESCIAMELLA:<br \/>\nMEZZO LITRO LATTE<br \/>\n35 GR FARINA<br \/>\n35 GR BURRO<br \/>\nSALE E NOCE MOSCATA<\/p>\n<p>Per preparare il pasticcio di maccheroni alla ferrarese abbiamo iniziato preparando il rag\u00f9 bianco.<br \/>\nIn padella abbiamo soffritto sedano, carota e cipolla finemente tritati, poi abbiamo aggiunto le carni e le salsicce spellate e sgranate. Quando la carne si \u00e8 colorata abbiamo tirato con un po\u2019 di vino bianco e lasciato cuocere.<br \/>\nA parte abbiamo preparato una besciamella classica. In un\u2019altra padella abbiamo trifolato i funghi, precedentemente ammollati, con olio, aglio e prezzemolo tritato.<br \/>\nNel frattempo abbiamo scottato i sedanini in acqua bollente e salata. Abbiamo scolato la pasta aggiungendo un filo d\u2019olio per non farla attaccare.<br \/>\nAbbiamo preparato la frolla unendo la farina con lo zucchero, la scorza di limone, il burro e le uova. Abbiamo lavorato su una spianatoia. Poi con l\u2019aiuto di un foglio di carta forno abbiamo steso il primo disco e lo abbiamo usato per rivestire una teglia imburrata e infarinata. Abbiamo bucato con i rebbi di una forchetta la sfoglia.<br \/>\nA questo punto abbiamo condito i sedanini con la carne, i funghi e la besciamella. Abbiamo riempito la teglia con la pasta e abbiamo chiuso il pasticcio con un secondo disco di frolla. Abbiamo bucherellato leggermente e infornato a 180\u00b0 per circa 35\/40 minuti.<\/p>\n<p>3)\tGLI ABBRACCI CON LA FROLLARINA<br \/>\n600 GR FARINA 00<br \/>\n250 GR ZUCCHERO SEMOLATO<br \/>\n250 GR BURRO A TEMPERATURA AMBIENTE<br \/>\n3 UOVA MEDIE<br \/>\n1 BUSTINA DI LIEVITO VANIGLIATO<br \/>\nMEZZO CUCCHIAIO DI CACAO AMARO<\/p>\n<p>Per preparare gli abbracci di frollarina abbiamo unito farina, zucchero e lievito su una spianatoia. Poi abbiamo aggiunto le uova intere ed il burro morbido. Con quattro mosse abbiamo impastato il tutto, infarinandoci leggermente le mani ogni tanto. Poi abbiamo preso met\u00e0 dell\u2019impasto e ci abbiamo aggiunto il cacao. Abbiamo amalgamato bene e con entrambi gli impasti abbiamo fatto dei cordoncini poco meno spessi di un mignolo, li abbiamo tagliati un po\u2019, li abbiamo intrecciati tra loro e arrotolati su s\u00e8 stessi. Infine abbiamo formato un cerchio con un bel buchetto al centro. Abbiamo disposto i biscotti su una teglia ricoperta di carta forno, spolverato con zucchero semolato e cotto al forno a 170\/180\u00b0 in forno statico per circa 15 minuti.<\/p>\n","protected":false},"excerpt":{"rendered":"\ufeff 1) LA RICETTA DI FABIO: FINOCCHI GRATINATI CON POMODORINI, CIPOLLA E OLIVE 1 FINOCCHIO 1 CIPOLLA 300 GR POMODORINI 60 GR OLIO EXTRA VERGINE D\u2019OLIVA 60 GR PANGRATTATO 50 GR PARMIGIANO 40 GR OLIVE NERE DENOCCIOLATE 1 CIUFFO PREZZEMOLO 1 SPICCHIO D\u2019AGLIO SALE E PEPE Per preparare i finocchi gratinati abbiamo pulito il finocchio [&hellip;]","protected":false},"author":6,"featured_media":278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puntate-2024-2025"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-content\/uploads\/sites\/79\/2024\/10\/pentolaquad.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/posts\/277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/comments?post=277"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/posts\/277\/revisions"}],"predecessor-version":[{"id":279,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/posts\/277\/revisions\/279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media\/278"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media?parent=277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/categories?post=277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/tags?post=277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}