{"id":119,"date":"2024-09-30T12:21:16","date_gmt":"2024-09-30T10:21:16","guid":{"rendered":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/?p=119"},"modified":"2024-09-30T12:26:44","modified_gmt":"2024-09-30T10:26:44","slug":"quel-che-bolle-in-pentola-tv2000-30-settembre-2024","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/2024\/09\/30\/quel-che-bolle-in-pentola-tv2000-30-settembre-2024\/","title":{"rendered":"30 settembre 2024"},"content":{"rendered":"<p>Quel che bolle in pentola (Tv2000) &#8211; 30 settembre 2024<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"Quel che bolle in pentola (Tv2000) - 30 settembre 2024\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/11FFTNcSIiU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>1) LA RICETTA DI FABIO: PIZZA DI POLENTA CON LA RICOTTA<br \/>\n300 GR RICOTTA<br \/>\nACQUA TIEPIDA<br \/>\nZUCCHERO<br \/>\nFARINA DI POLENTA<br \/>\nMEZZO CUCCHIAIO CANNELLA<br \/>\nUNA MANCIATA UVETTA<br \/>\nUNA MANCIATA PINOLI<br \/>\nBURRO Q.B.<br \/>\nPer preparare la pizza di polenta con ricotta abbiamo messo la ricotta scolata in una ciotola, l\u2019abbiamo stemperata con acqua tiepida. Poi abbiamo aggiunto la farina di mais, lo zucchero, la cannella e una manciata di uva sultanina, lavata e fatta rinvenire sempre in acqua tiepida. Abbiamo imburrato e infarinato una teglia e versato il composto. Questa pizza dolce non supera l\u2019altezza di un dito. Abbiamo cotto in forno per 45 minuti a 180\u00b0. Appena sfornata l\u2019abbiamo cosparsa con una manciata di pinoli.<\/p>\n<p>2) CROSTATA DI CARCIOFI<br \/>\nPER IL RIPIENO:<br \/>\n8 CARCIOFI<br \/>\nMEZZO DADO<br \/>\n1 CIPOLLA PICCOLA<br \/>\nSALE<br \/>\nOLIO<br \/>\n100 GR PROSCIUTTO COTTO<br \/>\n2 UOVA<br \/>\n50 GR PARMIGIANO<br \/>\n100 ML DI PANNA<br \/>\nVINO BIANCO<br \/>\nPER LA PASTA BRIS\u00c8:<br \/>\n300 GR FARINA<br \/>\n150 GR BURRO<br \/>\nUN PIZZICO DI SALE<br \/>\nMEZZO BICCHIERE D\u2019ACQUA<\/p>\n<p>Per preparare la crostata di carciofi abbiamo pulito i carciofi e lasciato in acqua e limone per non farli annerire. Poi li abbiamo tagliati a spicchi e sbollentati per qualche minuto.<br \/>\nIn una padella abbiamo soffritto la cipolla tagliata finemente, abbiamo aggiunto il prosciutto sminuzzato, poi i carciofi e mezzo dado.<br \/>\nAbbiamo sfumato con il vino e lasciato cuocere.<br \/>\nPer la brise\u00e8 abbiamo amalgamato il burro con la farina aiutandoci con un po\u2019 di acqua, senza lavorarla molto. L\u2019abbiamo lasciata riposare in frigo per circa mezz\u2019ora, poi l\u2019abbiamo stesa con le mani in una teglia imburrata e infarinata.<br \/>\nIn una ciotola abbiamo unito il condimento di carciofi e prosciutto con le uova, la panna, il parmigiano e un pizzico di sale. Abbiamo versato il composto sulla base di pasta bris\u00e9. Abbiamo infornato a 180\u00b0\/200\u00b0 per circa 40 minuti.<\/p>\n<p>3) ROLLE\u2019 DI SPINACI<br \/>\n\u00bc DI LATTE<br \/>\n120 GR FARINA<br \/>\n100 GR BURRO<br \/>\n2 UOVA<br \/>\n50 GR PARMIGIANO<br \/>\nNOCE MOSCATA<br \/>\n1 PRESA DI SALE<br \/>\n750 GR SPINACI FRESCHI<br \/>\nPer preparare il roll\u00e8 di spinaci abbiamo ripassato gli spinaci sbollentati in padella con un po\u2019 di burro. Abbiamo fatto una besciamella piuttosto consistente, nella quale abbiamo incorporato 2 uova e un po\u2019 di parmigiano. Abbiamo steso il composto in una placca da forno rivestita, livellando bene fino allo spessore di 1 cm. Abbiamo infornato per circa 15 minuti a 180\u00b0. Appena sfornato vi abbiamo disposto sopra gli spinaci tagliuzzati, abbiamo spolverato abbondante parmigiano e abbiamo arrotolato. Abbiamo chiuso con un foglio di alluminio e messo in frigo per circa 2 ore. Abbiamo tagliato il rotolo freddo a fette, le abbiamo messe in una teglia precedentemente imburrata, abbiamo cosparso di ulteriore parmigiano e infornato di nuovo per circa 15-20 minuti.<\/p>\n","protected":false},"excerpt":{"rendered":"Quel che bolle in pentola (Tv2000) &#8211; 30 settembre 2024 1) LA RICETTA DI FABIO: PIZZA DI POLENTA CON LA RICOTTA 300 GR RICOTTA ACQUA TIEPIDA ZUCCHERO FARINA DI POLENTA MEZZO CUCCHIAIO CANNELLA UNA MANCIATA UVETTA UNA MANCIATA PINOLI BURRO Q.B. Per preparare la pizza di polenta con ricotta abbiamo messo la ricotta scolata in [&hellip;]","protected":false},"author":6,"featured_media":120,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puntate-2024-2025"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-content\/uploads\/sites\/79\/2024\/09\/pentolaquad.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/posts\/119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/comments?post=119"}],"version-history":[{"count":2,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/posts\/119\/revisions"}],"predecessor-version":[{"id":126,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/posts\/119\/revisions\/126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media\/120"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/media?parent=119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/categories?post=119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/quelchebolleinpentola\/wp-json\/wp\/v2\/tags?post=119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}