{"id":9672,"date":"2017-06-12T14:47:26","date_gmt":"2017-06-12T12:47:26","guid":{"rendered":"http:\/\/staging.tv2000.it\/prega-con-noi\/?p=9672"},"modified":"2017-06-12T14:47:26","modified_gmt":"2017-06-12T12:47:26","slug":"sullastrada-domenica-della-santissima-trinita","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/prega-con-noi\/2017\/06\/12\/sullastrada-domenica-della-santissima-trinita\/","title":{"rendered":"#SullaStrada &#8211; Domenica della Santissima Trinit\u00e0"},"content":{"rendered":"<p style=\"text-align: justify;\">Don Dino Pirri per il commento al Vangelo della Santissima Trinit\u00e0 su Tv2000, sar\u00e0 presso \u201cUniversit\u00e0 Pontificia Salesiana\u201d che \u00e8 a servizio della societ\u00e0 e della Chiesa si propone come scopo caratterizzante di dedicare particolare attenzione allo studio e alla soluzione delle questioni inerenti l\u2019educazione e l\u2019azione pastorale specialmente tra i giovani e i ceti popolari, secondo lo spirito di Don Bosco. Papa Giovanni Paolo II durante la visita del 31 gennaio 1981, nella ricorrenza della festa di San Giovanni Bosco, esort\u00f2 \u201calla coscienza viva del compito ecclesiale primario\u201d dell\u2019Universit\u00e0, indicandone la particolare \u201cfunzione evangelizzatrice in chiave specificamente catechetica\u201d e riassumendone il progetto \u201ca favore dell\u2019uomo odierno e in particolare della giovent\u00f9\u201d nel programma: \u201cConoscere Dio nell\u2019uomo e conoscere l\u2019uomo in Dio\u201d; ci\u00f2 che, pi\u00f9 in concreto, comporta di \u201cconoscere Cristo nell\u2019uomo e conoscere l\u2019uomo in Cristo. Nel cortile della facolt\u00e0 di Scienze della Comunicazione Sociale dell\u2019Universit\u00e0 Pontificia Salesiana, don Dino commenta il Vangelo insieme agli studenti che vivono l\u2019universit\u00e0, raccogliendo le loro domande e rilanciandole a noi, affinch\u00e8 la Parola diventi provocazione e riflessione delle nostre giornate. Se vuoi intervenire attraverso facebook o twitter potete utilizzare: #SantissimaTrinit\u00e0 #PadreFiglioSpiritoSanto #sullastrada<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"#SullaStrada - Domenica della Santissima Trinit\u00e0\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/GSFcLWdngwk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"Don Dino Pirri per il commento al Vangelo della Santissima Trinit\u00e0 su Tv2000, sar\u00e0 presso \u201cUniversit\u00e0 Pontificia Salesiana\u201d che \u00e8 a servizio della societ\u00e0 e della Chiesa si propone come scopo caratterizzante di dedicare particolare attenzione allo studio e alla soluzione delle questioni inerenti l\u2019educazione e l\u2019azione pastorale specialmente tra i giovani e i ceti [&hellip;]","protected":false},"author":6,"featured_media":9673,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-9672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sulla-strada"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-content\/uploads\/sites\/23\/2017\/06\/14.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/9672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/comments?post=9672"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/9672\/revisions"}],"predecessor-version":[{"id":9674,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/9672\/revisions\/9674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/media\/9673"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/media?parent=9672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/categories?post=9672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/tags?post=9672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}