{"id":92763,"date":"2023-08-14T20:31:35","date_gmt":"2023-08-14T18:31:35","guid":{"rendered":"https:\/\/staging.tv2000.it\/prega-con-noi\/?p=92763"},"modified":"2023-08-14T20:31:35","modified_gmt":"2023-08-14T18:31:35","slug":"xix-domenica-del-tempo-ordinario","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/prega-con-noi\/2023\/08\/14\/xix-domenica-del-tempo-ordinario\/","title":{"rendered":"XIX domenica del Tempo Ordinario"},"content":{"rendered":"<p>Mt 14,22-33 Padre Jean Paul Hernandez commenta il Vangelo di Matteo della XIX domenica del tempo ordinario e ci mostra alcune rappresentazioni artistiche su Ges\u00f9 che cammina sulle acque. Vedendolo camminare sul mare, i discepoli furono sconvolti e dissero: \u00ab\u00c8 un fantasma!\u00bb e gridarono dalla paura. Pietro allora gli rispose: \u00abSignore, se sei tu, comandami di venire verso di te sulle acque\u00bb. Ed egli disse: \u00abVieni!\u00bb. Quelli che erano sulla barca si prostrarono davanti a lui, dicendo: \u00abDavvero tu sei Figlio di Dio!\u00bb. La vita \u00e8 paragonabile ad una traversata del mare e a volte, senza un aiuto esterno, non si riesce ad arrivare sulla sponda opposta. La fede \u00e8 l\u2019esperienza di un incontro con qualcuno che ti salva e Ges\u00f9 \u00e8 il nuovo Mos\u00e8. La vita \u00e8 fatta come le onde del mare con alti e bassi, l\u2019importante \u00e8 conoscere la direzione in cui si va. Tra le rappresentazioni artistiche padre Hernandez commenta tra le altre l\u2019opera Ges\u00f9 cammina sulle acque di Michail Aleksandrovic Vrubel.<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"Sulla Strada (TV2000) - XIX domenica del Tempo Ordinario\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/MQlAi9p-sOU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"Mt 14,22-33 Padre Jean Paul Hernandez commenta il Vangelo di Matteo della XIX domenica del tempo ordinario e ci mostra alcune rappresentazioni artistiche su Ges\u00f9 che cammina sulle acque. Vedendolo camminare sul mare, i discepoli furono sconvolti e dissero: \u00ab\u00c8 un fantasma!\u00bb e gridarono dalla paura. Pietro allora gli rispose: \u00abSignore, se sei tu, comandami [&hellip;]","protected":false},"author":6,"featured_media":92764,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-92763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sulla-strada"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-content\/uploads\/sites\/23\/2023\/08\/xix-1024x576.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/92763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/comments?post=92763"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/92763\/revisions"}],"predecessor-version":[{"id":92765,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/92763\/revisions\/92765"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/media\/92764"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/media?parent=92763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/categories?post=92763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/tags?post=92763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}