{"id":33043,"date":"2021-12-18T16:00:41","date_gmt":"2021-12-18T15:00:41","guid":{"rendered":"http:\/\/staging.tv2000.it\/prega-con-noi\/?p=33043"},"modified":"2021-12-20T10:59:45","modified_gmt":"2021-12-20T09:59:45","slug":"iv-domenica-di-avvento-anno-c","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/prega-con-noi\/2021\/12\/18\/iv-domenica-di-avvento-anno-c\/","title":{"rendered":"IV Domenica di Avvento (Anno C)"},"content":{"rendered":"<p>Lc 1, 39-45<\/p>\n<p>Dal Collegio Internazionale San Lorenzo da Brindisi padre Jean-Paul Hernandez commenta il Vangelo e illustra l\u2019arte sacra che ha ispirato. &#8220;In quei giorni Maria si alz\u00f2 e and\u00f2 in fretta verso la regione montuosa, in una citt\u00e0 di Giuda. Appena Elisabetta ebbe udito il saluto di Maria, il bambino sussult\u00f2 nel suo grembo&#8221;. Elisabetta che riconosce Ges\u00f9 in Maria rappresenta tutta Israele che attendeva la venuta del Messia. Si avvicina il Natale, tempo di visite e auguri, cerchiamo di riconoscere Ges\u00f9 in tutti quelli che incontriamo.<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"IV Domenica di Avvento (Anno C) \u2013 Vangelo domenica 19 dicembre 2021\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/UHzluNnlJK0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"Lc 1, 39-45 Dal Collegio Internazionale San Lorenzo da Brindisi padre Jean-Paul Hernandez commenta il Vangelo e illustra l\u2019arte sacra che ha ispirato. &#8220;In quei giorni Maria si alz\u00f2 e and\u00f2 in fretta verso la regione montuosa, in una citt\u00e0 di Giuda. Appena Elisabetta ebbe udito il saluto di Maria, il bambino sussult\u00f2 nel suo [&hellip;]","protected":false},"author":9,"featured_media":33044,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-33043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sulla-strada"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-content\/uploads\/sites\/23\/2021\/12\/sullastrada1812-1024x576.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/33043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/comments?post=33043"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/33043\/revisions"}],"predecessor-version":[{"id":33045,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/33043\/revisions\/33045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/media\/33044"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/media?parent=33043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/categories?post=33043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/tags?post=33043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}