{"id":24856,"date":"2020-03-07T17:30:29","date_gmt":"2020-03-07T16:30:29","guid":{"rendered":"http:\/\/staging.tv2000.it\/prega-con-noi\/?p=24856"},"modified":"2020-03-09T11:42:22","modified_gmt":"2020-03-09T10:42:22","slug":"sullastrada-ii-domenica-di-quaresima-2","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/prega-con-noi\/2020\/03\/07\/sullastrada-ii-domenica-di-quaresima-2\/","title":{"rendered":"#SullaStrada &#8211; II Domenica di Quaresima"},"content":{"rendered":"<p>Nella seconda domenica di Quaresima percorriamo con padre Giulio Michelini il primitivo ingresso alla Basilica romana di Sant\u2019Agnese fuori le mura, dove sui muri si possono ancora vedere i marmi con le iscrizioni che ne fanno una vera biblioteca di fede nella Resurrezione. In questa basilica antica, sorta sulle spoglie di una giovane martire dei primi secoli, padre Giulio Michelini commenta il Vangelo di questa domenica, con l\u2019episodio della Trasfigurazione di Ges\u00f9: una narrazione profetica, perch\u00e9 Ges\u00f9 si mostra nello splendore dell\u2019eternit\u00e0. Pi\u00f9 che di una Trasfigurazione dovremmo piuttosto parlare di una trasformazione di Ges\u00f9 negli occhi dei discepoli. Da questo momento Pietro e i suoi compagni potranno guardare al Messia in modo nuovo, anche se la loro piccolezza impedisce di comprendere appieno la portata dell\u2019avvenimento cui sono chiamati come testimoni. Come noi, i prescelti, gli amici pi\u00f9 cari di Cristo si beano della sua compagnia, di quella dei profeti, e chiedono di restare insieme, da soli, a godere dello splendore della grazia. Non avevano capito, e infatti sono ancora colti da timore. Per questo Ges\u00f9 li invita a non parlare con nessuno di quello che avevano visto: ci vuole il Suo Spirito, per aprire la ragione e il cuore al mistero pi\u00f9 grande della fede.<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"#SullaStrada - II Domenica di Quaresima\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/BtzAb-1C0X4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"Nella seconda domenica di Quaresima percorriamo con padre Giulio Michelini il primitivo ingresso alla Basilica romana di Sant\u2019Agnese fuori le mura, dove sui muri si possono ancora vedere i marmi con le iscrizioni che ne fanno una vera biblioteca di fede nella Resurrezione. In questa basilica antica, sorta sulle spoglie di una giovane martire dei [&hellip;]","protected":false},"author":9,"featured_media":24861,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-24856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sulla-strada"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-content\/uploads\/sites\/23\/2020\/03\/sullastrada15-1024x580.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/24856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/comments?post=24856"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/24856\/revisions"}],"predecessor-version":[{"id":24857,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/24856\/revisions\/24857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/media\/24861"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/media?parent=24856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/categories?post=24856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/tags?post=24856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}