{"id":23809,"date":"2020-01-04T16:30:24","date_gmt":"2020-01-04T15:30:24","guid":{"rendered":"http:\/\/staging.tv2000.it\/prega-con-noi\/?p=23809"},"modified":"2020-01-07T09:54:15","modified_gmt":"2020-01-07T08:54:15","slug":"sullastrada-ii-domenica-dopo-natale","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/prega-con-noi\/2020\/01\/04\/sullastrada-ii-domenica-dopo-natale\/","title":{"rendered":"#SullaStrada &#8211; II Domenica dopo Natale"},"content":{"rendered":"<p>In questa prima domenica del nuovo anno, vigilia della manifestazione del Signore, l\u2019Epifania, si legge nella liturgia il primo capitolo di san Giovanni. Un brano di alta teologia, un brano capace di intercettare il bisogno di infinito e il senso religioso anche dei pi\u00f9 colto tra i \u201cgentili\u201d, che aspettavano una risposta alle domande pi\u00f9 profonde dell\u2019uomo. Il verbo, il L\u00f2gos, che gli uomini hanno cercato nella filosofia, si \u00e8 fatto incontrare. \u201cIl Dio che cerate senza conoscerlo\u201d, diceva san Paolo, si \u00e8 fatto conoscere, nel tempo e nella storia. Et incarnatum est: \u00e8 il cuore della preghiera dell\u2019Angelus, che scandiva il lavoro al mezzogiorno che sentiamo recitare ogni domenica dal papa. Un testo poetico, altissimo, filosofico, difficile da spiegare, ma in questo esercizio si impegna padre Giulio Michelini, biblista, docente, nel suo commento raccolto nella basilica romana di san Lorenzo fuori le Mura. La Chiesa che sotto il porticato custodisce le spoglie del padre della nostra democrazia, Alcide De Gasperi.<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"#SullaStrada - II Domenica dopo Natale\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/2SDmGVZlhuY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"In questa prima domenica del nuovo anno, vigilia della manifestazione del Signore, l\u2019Epifania, si legge nella liturgia il primo capitolo di san Giovanni. Un brano di alta teologia, un brano capace di intercettare il bisogno di infinito e il senso religioso anche dei pi\u00f9 colto tra i \u201cgentili\u201d, che aspettavano una risposta alle domande pi\u00f9 [&hellip;]","protected":false},"author":9,"featured_media":23810,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-23809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sulla-strada"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-content\/uploads\/sites\/23\/2020\/01\/sullastrada0401-1024x574.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/23809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/comments?post=23809"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/23809\/revisions"}],"predecessor-version":[{"id":23811,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/23809\/revisions\/23811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/media\/23810"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/media?parent=23809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/categories?post=23809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/tags?post=23809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}