{"id":19641,"date":"2019-04-29T10:44:56","date_gmt":"2019-04-29T08:44:56","guid":{"rendered":"http:\/\/staging.tv2000.it\/prega-con-noi\/?p=19641"},"modified":"2019-04-29T10:44:56","modified_gmt":"2019-04-29T08:44:56","slug":"sullastrada-ii-domenica-di-pasqua-e-della-divina-misericordia","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/prega-con-noi\/2019\/04\/29\/sullastrada-ii-domenica-di-pasqua-e-della-divina-misericordia\/","title":{"rendered":"#SullaStrada &#8211; II Domenica di Pasqua e della Divina Misericordia"},"content":{"rendered":"<p>Padre Giulio Michelini, biblista e teologo, nell\u2019appuntamento di Sulla Strada, il commento al Vangelo di TV2000, spiega il Vangelo di Giovanni:<\/p>\n<p>\u201cGes\u00f9 disse loro di nuovo: \u00abPace a voi! Come il Padre ha mandato me, anche io mando voi\u00bb. Detto questo, soffi\u00f2 e disse loro: \u00abRicevete lo Spirito Santo. A coloro a cui perdonerete i peccati, saranno perdonati; a coloro a cui non perdonerete, non saranno perdonati\u00bb.\u201d<\/p>\n<p>Dalla chiesa di San Gregorio Magno al Celio, situato nel centro storico di Roma. Si trova sul Celio, di fronte al Palatino ed accanto al Circo Massimo.<\/p>\n<p>I disegni sono di Stefania Pedna.<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"#SullaStrada - II Domenica di Pasqua e della Divina Misericordia\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/YugrGczaZHU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"Padre Giulio Michelini, biblista e teologo, nell\u2019appuntamento di Sulla Strada, il commento al Vangelo di TV2000, spiega il Vangelo di Giovanni: \u201cGes\u00f9 disse loro di nuovo: \u00abPace a voi! Come il Padre ha mandato me, anche io mando voi\u00bb. Detto questo, soffi\u00f2 e disse loro: \u00abRicevete lo Spirito Santo. A coloro a cui perdonerete i [&hellip;]","protected":false},"author":6,"featured_media":19642,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-19641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sulla-strada"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-content\/uploads\/sites\/23\/2019\/04\/Sullastrada-28-aprile-2019-1024x576.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/19641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/comments?post=19641"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/19641\/revisions"}],"predecessor-version":[{"id":19643,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/19641\/revisions\/19643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/media\/19642"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/media?parent=19641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/categories?post=19641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/tags?post=19641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}