{"id":11232,"date":"2017-10-16T16:56:33","date_gmt":"2017-10-16T14:56:33","guid":{"rendered":"http:\/\/staging.tv2000.it\/prega-con-noi\/?p=11232"},"modified":"2017-10-16T16:57:16","modified_gmt":"2017-10-16T14:57:16","slug":"sullastrada-xxvii-domenica-del-tempo-ordinario","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/prega-con-noi\/2017\/10\/16\/sullastrada-xxvii-domenica-del-tempo-ordinario\/","title":{"rendered":"#SullaStrada &#8211; XXVII Domenica del Tempo Ordinario"},"content":{"rendered":"<p>Don Dino Pirri per il commento al Vangelo della XXVII domenica del tempo ordinario, sar\u00e0 nella \u201cParrocchia del Presidio\u201d presso il Comprensorio Citt\u00e0 Militare Cecchignola. La parrocchia oltre ad accompagnare i militari, offre il sostegno di un accompagnamento spirituale ed umano anche alle famiglie che vivono intorno alla citt\u00e0 militare, in particolare quelle che vivono in difficolt\u00e0 partendo da fatti e bisogni concreti, con l\u2019aiuto della Caritas diocesana. Don Dino commenta il Vangelo dell\u2019ultima domenica di settembre, insieme ad una comunit\u00e0 frequentata da giovani e animatori, raccogliendo le loro domande e rilanciandole a noi, affinch\u00e8 la Parola diventi provocazione e riflessione delle nostre giornate. Siamo operai della prima o dell\u2019ultima ora? E valiamo di pi\u00f9 o di meno, o i nostri tempi e la nostra giustizia non sono quelli di Dio? E perch\u00e9? Vi aspettiamo la prossima settimana. Buona inizio del mese del Rosario! Se vuoi intervenire attraverso facebook o twitter puoi utilizzare: <a class=\"yt-simple-endpoint style-scope yt-formatted-string\" href=\"https:\/\/www.youtube.com\/results?search_query=%23vigna\">#vigna<\/a> <a class=\"yt-simple-endpoint style-scope yt-formatted-string\" href=\"https:\/\/www.youtube.com\/results?search_query=%23figlio\">#figlio<\/a> <a class=\"yt-simple-endpoint style-scope yt-formatted-string\" href=\"https:\/\/www.youtube.com\/results?search_query=%23sullastrada\">#sullastrada<\/a><\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"#SullaStrada - XXVII Domenica del Tempo Ordinario\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/Q_j2b6Qoy0A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"Don Dino Pirri per il commento al Vangelo della XXVII domenica del tempo ordinario, sar\u00e0 nella \u201cParrocchia del Presidio\u201d presso il Comprensorio Citt\u00e0 Militare Cecchignola. La parrocchia oltre ad accompagnare i militari, offre il sostegno di un accompagnamento spirituale ed umano anche alle famiglie che vivono intorno alla citt\u00e0 militare, in particolare quelle che vivono [&hellip;]","protected":false},"author":6,"featured_media":7502,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8,1],"tags":[],"class_list":["post-11232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sulla-strada","category-varie"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-content\/uploads\/sites\/23\/2016\/12\/Sulla-Strada-17-Dic.png","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/11232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/comments?post=11232"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/11232\/revisions"}],"predecessor-version":[{"id":11233,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/11232\/revisions\/11233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/media\/7502"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/media?parent=11232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/categories?post=11232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/tags?post=11232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}