{"id":11228,"date":"2017-10-16T16:53:43","date_gmt":"2017-10-16T14:53:43","guid":{"rendered":"http:\/\/staging.tv2000.it\/prega-con-noi\/?p=11228"},"modified":"2017-10-16T16:53:43","modified_gmt":"2017-10-16T14:53:43","slug":"sullastrada-xxv-domenica-del-tempo-ordinario","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/prega-con-noi\/2017\/10\/16\/sullastrada-xxv-domenica-del-tempo-ordinario\/","title":{"rendered":"#SullaStrada: XXV Domenica del Tempo Ordinario"},"content":{"rendered":"<p style=\"text-align: justify;\">Don Dino Pirri per il commento al Vangelo della XXV domenica del tempo ordinario, sar\u00e0 nella \u201cParrocchia del Presidio\u201d presso il Comprensorio Citt\u00e0 Militare Cecchignola. La parrocchia oltre ad accompagnare i militari, offre il sostegno di un accompagnamento spirituale ed umano anche alle famiglie che vivono intorno alla citt\u00e0 militare, in particolare quelle che vivono in difficolt\u00e0 partendo da fatti e bisogni concreti, con l\u2019aiuto della Caritas diocesana. Don Dino commenta il Vangelo dell\u2019ultima domenica di settembre, insieme ad una comunit\u00e0 frequentata da giovani e animatori, raccogliendo le loro domande e rilanciandole a noi, affinch\u00e8 la Parola diventi provocazione e riflessione delle nostre giornate. Siamo operai della prima o dell\u2019ultima ora? E valiamo di pi\u00f9 o di meno, o i nostri tempi e la nostra giustizia non sono quelli di Dio? E perch\u00e9? Vi aspettiamo la prossima settimana. Buona domenica! Se vuoi intervenire attraverso facebook o twitter puoi utilizzare: <a class=\"yt-simple-endpoint style-scope yt-formatted-string\" href=\"https:\/\/www.youtube.com\/results?search_query=%23vigna\">#vigna<\/a> <a class=\"yt-simple-endpoint style-scope yt-formatted-string\" href=\"https:\/\/www.youtube.com\/results?search_query=%23primieultimi\">#primieultimi<\/a><\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"#SullaStrada: XXV Domenica del Tempo Ordinario\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/BMxbcxTRs0s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"Don Dino Pirri per il commento al Vangelo della XXV domenica del tempo ordinario, sar\u00e0 nella \u201cParrocchia del Presidio\u201d presso il Comprensorio Citt\u00e0 Militare Cecchignola. La parrocchia oltre ad accompagnare i militari, offre il sostegno di un accompagnamento spirituale ed umano anche alle famiglie che vivono intorno alla citt\u00e0 militare, in particolare quelle che vivono [&hellip;]","protected":false},"author":6,"featured_media":3786,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-11228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sulla-strada"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-content\/uploads\/sites\/23\/2016\/02\/sulla-strada.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/11228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/comments?post=11228"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/11228\/revisions"}],"predecessor-version":[{"id":11229,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/posts\/11228\/revisions\/11229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/media\/3786"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/media?parent=11228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/categories?post=11228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/prega-con-noi\/wp-json\/wp\/v2\/tags?post=11228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}