{"id":105709,"date":"2025-05-19T13:59:26","date_gmt":"2025-05-19T11:59:26","guid":{"rendered":"https:\/\/staging.tv2000.it\/ilmiomedico\/?post_type=video&#038;p=105709"},"modified":"2025-05-19T13:59:26","modified_gmt":"2025-05-19T11:59:26","slug":"grasso-addominale-la-misura-della-nostra-salute","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/ilmiomedico\/video\/grasso-addominale-la-misura-della-nostra-salute\/","title":{"rendered":"Grasso addominale, la misura della nostra salute"},"content":{"rendered":"<p>Il grasso addominale non \u00e8 solo una questione estetica: pu\u00f2 essere un indicatore importante del nostro stato di salute. Ma quando diventa davvero pericoloso? E perch\u00e9 la nostra pancia cambia nel corso della giornata?<br \/>\nIl prof. Pier Luigi Rossi, medico specialista in scienze dell\u2019alimentazione, spiega come effettuare una semplice misurazione a casa per valutare il rischio e cosa possiamo fare per dire addio alla pancetta in modo sano ed efficace<\/p>\n<p>Rivedi la puntata integrale su Play2000:<\/p>\n<p><a href=\"https:\/\/www.play2000.it\/detail\/9?episode_id=17912&amp;season_id=724\">https:\/\/www.play2000.it\/detail\/9?episode_id=17912&amp;season_id=724<\/a><\/p>\n","protected":false},"featured_media":105710,"comment_status":"open","ping_status":"closed","template":"","tags":[],"class_list":["post-105709","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-curarsi-a-tavola"],"acf":[],"aioseo_notices":[],"url_youtube":"yyuEnDa6GF0","featured_image_url":"https:\/\/i.ytimg.com\/vi\/yyuEnDa6GF0\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/video\/105709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/comments?post=105709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/media\/105710"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/media?parent=105709"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/tags?post=105709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}