{"id":11,"date":"2015-02-18T09:48:51","date_gmt":"2015-02-18T08:48:51","guid":{"rendered":"http:\/\/staging.tv2000.it\/ilmiomedico\/?page_id=11"},"modified":"2023-10-23T15:12:48","modified_gmt":"2023-10-23T13:12:48","slug":"il-programma","status":"publish","type":"page","link":"https:\/\/staging.tv2000.it\/ilmiomedico\/il-programma\/","title":{"rendered":"Il programma"},"content":{"rendered":"<p><a href=\"http:\/\/staging.tv2000.it\/ilmiomedico\/wp-content\/uploads\/sites\/8\/2015\/02\/il-mio-medico-studio.jpg\"><img decoding=\"async\" class=\"alignnone wp-image-2624 size-full\" src=\"http:\/\/staging.tv2000.it\/ilmiomedico\/wp-content\/uploads\/sites\/8\/2015\/02\/il-mio-medico-studio.jpg\" alt=\"\" width=\"800\" height=\"315\" srcset=\"https:\/\/staging.tv2000.it\/ilmiomedico\/wp-content\/uploads\/sites\/8\/2015\/02\/il-mio-medico-studio.jpg 800w, https:\/\/staging.tv2000.it\/ilmiomedico\/wp-content\/uploads\/sites\/8\/2015\/02\/il-mio-medico-studio-300x118.jpg 300w, https:\/\/staging.tv2000.it\/ilmiomedico\/wp-content\/uploads\/sites\/8\/2015\/02\/il-mio-medico-studio-768x302.jpg 768w, https:\/\/staging.tv2000.it\/ilmiomedico\/wp-content\/uploads\/sites\/8\/2015\/02\/il-mio-medico-studio-69x27.jpg 69w, https:\/\/staging.tv2000.it\/ilmiomedico\/wp-content\/uploads\/sites\/8\/2015\/02\/il-mio-medico-studio-280x110.jpg 280w, https:\/\/staging.tv2000.it\/ilmiomedico\/wp-content\/uploads\/sites\/8\/2015\/02\/il-mio-medico-studio-650x256.jpg 650w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\u201cIl mio medico\u201d \u00e8 il programma di informazione medica di TV2000 che porta la cultura della salute dagli ambulatori direttamente nelle case degli spettatori, con Monica Di Loreto.<br \/>\nConsigli pratici e ultime novit\u00e0 dal mondo della medicina e del benessere, raccontate con un linguaggio semplice direttamente dalle eccellenze della sanit\u00e0 italiana.<br \/>\nSpazio all\u2019alimentazione, alla medicina specialistica, fino all\u2019attivit\u00e0 fisica e alla fitoterapia, per una cura della salute a tutto tondo.<br \/>\nUna guida quotidiana che promuove la prevenzione e uno stile di vita sano, per chiarire i dubbi e le fake news pi\u00f9 comuni.<\/p>\n<p>Dal luned\u00ec al venerd\u00ec, alle ore 9.45<br \/>\nScritto da Fausto Della Ceca<\/p>\n","protected":false},"excerpt":{"rendered":"\u201cIl mio medico\u201d \u00e8 il programma di informazione medica di TV2000 che porta la cultura della salute dagli ambulatori direttamente nelle case degli spettatori, con Monica Di Loreto. Consigli pratici e ultime novit\u00e0 dal mondo della medicina e del benessere, raccontate con un linguaggio semplice direttamente dalle eccellenze della sanit\u00e0 italiana. Spazio all\u2019alimentazione, alla medicina [&hellip;]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-11","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/pages\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/staging.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":30,"href":"https:\/\/staging.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/pages\/11\/revisions"}],"predecessor-version":[{"id":66,"href":"https:\/\/staging.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/pages\/11\/revisions\/66"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/ilmiomedico\/wp-json\/wp\/v2\/media?parent=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}