{"id":6125,"date":"2018-03-16T12:43:44","date_gmt":"2018-03-16T11:43:44","guid":{"rendered":"http:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/?p=6125"},"modified":"2018-03-23T13:19:24","modified_gmt":"2018-03-23T12:19:24","slug":"il-diario-di-papa-francesco-dal-19-al-23-marzo","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/2018\/03\/16\/il-diario-di-papa-francesco-dal-19-al-23-marzo\/","title":{"rendered":"Il Diario di Papa Francesco. Dal 19 al 23 marzo"},"content":{"rendered":"<p><em><strong><img decoding=\"async\" class=\"aligncenter size-full wp-image-6118\" src=\"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2018\/03\/WhatsApp-Image-2018-03-15-at-17.58.481.jpeg\" alt=\"\" width=\"1328\" height=\"747\" srcset=\"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2018\/03\/WhatsApp-Image-2018-03-15-at-17.58.481.jpeg 1328w, https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2018\/03\/WhatsApp-Image-2018-03-15-at-17.58.481-300x169.jpeg 300w, https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2018\/03\/WhatsApp-Image-2018-03-15-at-17.58.481-768x432.jpeg 768w, https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2018\/03\/WhatsApp-Image-2018-03-15-at-17.58.481-1024x576.jpeg 1024w, https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2018\/03\/WhatsApp-Image-2018-03-15-at-17.58.481-48x27.jpeg 48w, https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2018\/03\/WhatsApp-Image-2018-03-15-at-17.58.481-280x158.jpeg 280w, https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2018\/03\/WhatsApp-Image-2018-03-15-at-17.58.481-650x366.jpeg 650w\" sizes=\"(max-width: 1328px) 100vw, 1328px\" \/>Luned\u00ec 19 marzo<\/strong><\/em><\/p>\n<p><strong>SPECIALE PRE-SINODO<\/strong><\/p>\n<p><strong>Il Papa incontra i giovani<\/strong><\/p>\n<p><em>Diretta dalle ore 8.40 alle 12.00<\/em><\/p>\n<p>Papa Francesco incontrer\u00e0 300 giovani, tra i 16 e 29 anni, arrivati da tutto il mondo, per inaugurare la settimana di preparazione al Sinodo dei Vescovi che si terr\u00e0 a ottobre, con la volont\u00e0 di ascoltare la loro voce sul tema fede e discernimento vocazionale\u201d.<\/p>\n<p><em>In studio:<\/em> <strong>Padre Lello Lanzilli sj <\/strong>gesuita, <strong>Lorenzo Zardi<\/strong> Vice Segretario Msac &#8211; Movimento Studenti di Azione Cattolica, <strong>Sofia Gomez Robisco <\/strong>Coordinatrice del gruppo Pietre Vive di Madrid,\u00a0 e\u00a0<strong>Emilio Cosentino,\u00a0<\/strong>Coordinatore gruppo giovani &#8211; Comunit\u00e0 Cattolica Shalom<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><em><strong>Marted\u00ec 20 marzo<\/strong><\/em><\/p>\n<p><strong>UN PAPA FUORI PROGRAMMA<\/strong><\/p>\n<p>A cinque anni dall\u2019inizio del suo pontificato, Papa Francesco \u00e8 ormai riconosciuto come il Papa delle novit\u00e0, dalla visione dirompente applicata ai gesti di ogni giorno nella Chiesa, nella societ\u00e0 e nelle relazioni.<br \/>\n<strong>Gerolamo Fazzini <\/strong>e<strong> Stefano Femminis<\/strong> nel libro \u201c<em>Francesco. Il Papa delle prime volte\u201d<\/em> (ed. San Paolo) delineano i tratti distintivi dell\u2019inedito, avvalendosi dei contributi di alcuni dei massimi esperti di Chiesa che seguono da vicino il papa argentino.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Mercoled\u00ec 21 marzo<\/strong><\/em><\/p>\n<p><strong>UDIENZA GENERALE:<\/strong><\/p>\n<p><strong>La Messa in famiglia<\/strong><\/p>\n<p>Proseguono le catechesi sulla Santa Messa di Papa Francesco. L\u2019interpretazione delle parole del Papa del giorno \u00e8 affidata alla coppia <strong>Robert Cheaib e Camilla Carrington.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><em><strong>Gioved\u00ec 22 marzo<\/strong><\/em><\/p>\n<p><strong>L\u2019EREDITA\u2019 DI PADRE PIO<\/strong><\/p>\n<p>Il 17 marzo Papa Bergoglio si recher\u00e0 a <strong>Pietrelcina e a San Giovanni Rotondo<\/strong> per il Centenario dell\u2019apparizione delle stimmate di San Pio e nel 50.mo anniversario della morte di San Pio da Pietrelcina.<br \/>\nA testimonianza della visita pastorale e della figura del santo, <strong>Padre <em>Marciano Morra,<\/em><\/strong><em> ultimo frate che ha vissuto con <\/em>Padre Pio, <em>e <\/em><strong>Stefano Campanella<\/strong>, giornalista, scrittore, direttore di Padre Pio Tv e responsabile ufficio stampa della Provincia religiosa di Sant\u2019Angelo e Padre Pio dei Frati Minori Cappuccini.<\/p>\n<p><strong>\u00a0<\/strong><strong>\u00a0<\/strong><\/p>\n<p><em><strong>Venerd\u00ec 23 marzo<\/strong><\/em><\/p>\n<p><strong>CONCLUSIONE DEL PRE-SINODO<\/strong><\/p>\n<p>Puntata dedicata alla conclusione della settimana pre-sinodale con l\u2019analisi di alcuni dei partecipanti all\u2019incontro: <strong>Don Giordano Goccini<\/strong>, Direttore della Pastorale giovanile Reggio Emilia \u2013 Guastalla; <strong>Gabriella Serra<\/strong> Presidente Nazionale Femminile della Fuci &#8211; Federazione universitaria cattolica italiana e <strong>Gioele Anni<\/strong>, Consigliere Nazionale per il settore giovani di Azione Cattolica e <strong>Andrea Castagnetti<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"Luned\u00ec 19 marzo SPECIALE PRE-SINODO Il Papa incontra i giovani Diretta dalle ore 8.40 alle 12.00 Papa Francesco incontrer\u00e0 300 giovani, tra i 16 e 29 anni, arrivati da tutto il mondo, per inaugurare la settimana di preparazione al Sinodo dei Vescovi che si terr\u00e0 a ottobre, con la volont\u00e0 di ascoltare la loro voce [&hellip;]","protected":false},"author":6,"featured_media":5691,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[117],"tags":[],"class_list":["post-6125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2018\/02\/Il-diario-di-papa-francesco-07-1024x576.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/6125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/comments?post=6125"}],"version-history":[{"count":5,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/6125\/revisions"}],"predecessor-version":[{"id":6180,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/6125\/revisions\/6180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/media\/5691"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/media?parent=6125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/categories?post=6125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/tags?post=6125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}