{"id":45595,"date":"2025-04-29T10:03:55","date_gmt":"2025-04-29T08:03:55","guid":{"rendered":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/?p=45595"},"modified":"2025-04-30T19:59:58","modified_gmt":"2025-04-30T17:59:58","slug":"verso-il-conclave","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/2025\/04\/29\/verso-il-conclave\/","title":{"rendered":"Verso il Conclave <br> Le chiese africane"},"content":{"rendered":"<div class=\"rwd-video\"><iframe title=\"Play 2000\" src=\"https:\/\/www.play2000.it\/play\/episode\/16982?startAt=0&amp;backToUrl=%2Fdetail%2F531\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\"><\/span><\/iframe><\/div>\n<p>Il tema della prima puntata del programma &#8220;Verso il Conclave&#8221;,&nbsp; in onda il 28 aprile, sono le chiese africane.<\/p>\n<p>\u00c8 il continente dove la Chiesa cresce pi\u00f9 velocemente, l\u2019Africa, che ospita ormai il 20% dei fedeli cattolici nel mondo: 281 milioni di persone e il dono di una fede giovane e vitale, al primo posto anche nell\u2019aumento delle vocazioni sacerdotali.<\/p>\n<p>Qui la Chiesa deve confrontarsi con una storia segnata dalla tratta dei neri e dalla colonizzazione, oltre che con le contraddizioni del tribalismo e della rivalit\u00e0 etnica.<\/p>\n<p>Dall\u2019Africa si preparano a entrare nella Cappella Sistina per il conclave 18 cardinali elettori, dalla Nigeria all\u2019Etiopia, dal Madagascar a Capo Verde.<\/p>\n<p>Tra i nomi di peso c\u2019\u00e8 quello di <strong>Fridolin Ambongo Besungu<\/strong>, 65 anni, frate minore cappuccino arcivescovo di Kinshasa \u2013 capitale della martoriata Repubblica Democratica del Congo, dilaniata da guerre e sfruttamento delle risorse.<\/p>\n<p>Creato cardinale da Francesco il 5 ottobre 2019 Ambongo Besungu \u00e8 considerato \u201cl\u2019uomo forte\u201d del cattolicesimo africano: \u00e8 presidente del Simposio delle conferenze episcopali d\u2019Africa e Madagascar (il SECAM) e Francesco nel 2020 lo ha voluto nel Consiglio dei nove cardinali che accompagnano il papa nella riforma della Chiesa.<\/p>\n<p>Del cardinale Besungu papa Bergoglio ha apprezzato il ruolo di mediatore di pace, le critiche contro la corruzione del potere politico e contro il \u201ccolonialismo economico\u201d.<\/p>\n<p>Un altro cardinale che conosce bene l\u2019orrore della guerra \u00e8 <strong>Dieudonn\u00e9 Nzapalainga<\/strong>, 58 anni, missionario spiritano, arcivescovo di Bangui, capitale della Repubblica Centrafricana dilaniata dalla guerra civile.<\/p>\n<p>Da sempre in prima fila nel processo di riconciliazione del suo Paese, il quotidiano francese <em>Le Monde<\/em> l\u2019ha definito \u00abuno dei tre saggi di Bangui\u00bb insieme a un imam e un pastore evangelico con cui ha fondato la \u201cPiattaforma interreligiosa per la pace in Centrafrica\u201d, che ha ottenuto il Premio per i diritti umani delle Nazioni Unite nel 2015.<\/p>\n<p>\u201cSe apriamo le porte dei cuori alla misericordia, la pace arriver\u00e0 anche qui\u201d. Cos\u00ec scrisse l\u2019Arcivescovo Nzapalainga ai fedeli dopo quel 29 novembre 2015 in cui il papa apr\u00ec la Porta Santa del Giubileo straordinario della Misericordia proprio a Bangui. Francesco lo ha creato cardinale l\u2019anno successivo, il 19 novembre 2016.<\/p>\n<p>Tra i cardinali africani di pi\u00f9 lungo corso c\u2019\u00e8 invece <strong>Peter Kodwo Appiah Turkson<\/strong>, 77 anni, originario del Ghana.<\/p>\n<p>Cardinale dal 2003 per volere di Giovanni Paolo II, era nel conclave dell\u2019aprile 2005 che ha eletto papa Benedetto XVI e anche in quello del marzo 2013 che ha eletto papa Francesco. Uomo di grande esperienza in Curia, dove ha guidato diversi uffici, \u00e8 stato uno dei cardinali pi\u00f9 vicini e ascoltati da Francesco che non a caso lo ha nominato prefetto del Dicastero per la promozione dello sviluppo umano integrale, incaricato di alcuni dei temi che stavano pi\u00f9 a cuore al papa: ambiente ed ecologia, flussi migratori, uguaglianza e giustizia economica.<\/p>\n<p>Oggi \u00e8 cancelliere della Pontificia accademia delle Scienze e della Pontifica Accademia delle Scienze sociali.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p><em>Il programma quotidiano di Tv2000 per conoscere curiosit\u00e0, luoghi e modalit\u00e0 del cammino che condurr\u00e0 all\u2019elezione del nuovo Pontefice<\/em><\/p>\n<p>L\u2019eredit\u00e0 di Papa Francesco, i frutti del Sinodo, le attese delle Chiese particolari, le questioni all\u2019attenzione del Collegio Cardinalizio: \u201cVerso il Conclave\u201d \u00e8 il nuovo programma quotidiano di Tv2000 per conoscere curiosit\u00e0, luoghi e modalit\u00e0 del cammino che condurr\u00e0 all\u2019elezione del nuovo Pontefice. Ogni puntata sar\u00e0 dedicata ad un continente, per scoprire i volti, le parole e la storia dei Cardinali elettori arrivati dalle terre vicine e lontane e per rivivere la testimonianza resa in quelle terre da Papa Bergoglio in occasione dei suoi viaggi.<\/p>\n<p>Di Dario Quarta e Gennaro Ferrara<br \/>\nScritto con Ezio D\u2019Eusanio, Francesco Esposito e Barbara Liverzani<br \/>\nConduce Gennaro Ferrara<br \/>\nIn onda da luned\u00ec al venerd\u00ec alle 16.30<\/p>\n","protected":false},"excerpt":{"rendered":"\ufeff Il tema della prima puntata del programma &#8220;Verso il Conclave&#8221;,&nbsp; in onda il 28 aprile, sono le chiese africane. \u00c8 il continente dove la Chiesa cresce pi\u00f9 velocemente, l\u2019Africa, che ospita ormai il 20% dei fedeli cattolici nel mondo: 281 milioni di persone e il dono di una fede giovane e vitale, al primo [&hellip;]","protected":false},"author":9,"featured_media":45597,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[180],"tags":[181],"class_list":["post-45595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-verso-il-conclave","tag-conclave"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2025\/04\/versoconclave2804.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/45595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/comments?post=45595"}],"version-history":[{"count":9,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/45595\/revisions"}],"predecessor-version":[{"id":45688,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/45595\/revisions\/45688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/media\/45597"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/media?parent=45595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/categories?post=45595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/tags?post=45595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}