{"id":42296,"date":"2025-03-06T22:35:43","date_gmt":"2025-03-06T21:35:43","guid":{"rendered":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/?p=42296"},"modified":"2025-03-06T22:36:20","modified_gmt":"2025-03-06T21:36:20","slug":"60-anni-fa-la-prima-messa-in-italiano","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/2025\/03\/06\/60-anni-fa-la-prima-messa-in-italiano\/","title":{"rendered":"60 anni fa la prima messa in italiano"},"content":{"rendered":"<p>Esattamente oggi, sessant&#8217;anni fa, il Papa Paolo VI nella parrocchia romana di Ognissanti celebrava la prima Messa in lingua italiana. Un evento importante perch\u00e9, abbandonato il latino, la Chiesa cominciava a rivolgersi alla gente con la lingua usata dalla gente. Al Diario lo ricordiamo con suor Elena Massimi, liturgista dell Pontificia Universit\u00e0 Salesiana.<\/p>\n<div class=\"rwd-video\"><iframe title=\"Play 2000\" src=\"https:\/\/www.play2000.it\/play\/episode\/14647?startAt=0&amp;backToUrl=%2Fdetail%2F13%3Fepisode_id%3D14647%26season_id%3D646\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"Esattamente oggi, sessant&#8217;anni fa, il Papa Paolo VI nella parrocchia romana di Ognissanti celebrava la prima Messa in lingua italiana. Un evento importante perch\u00e9, abbandonato il latino, la Chiesa cominciava a rivolgersi alla gente con la lingua usata dalla gente. Al Diario lo ricordiamo con suor Elena Massimi, liturgista dell Pontificia Universit\u00e0 Salesiana. \ufeff\ufeff\ufeff","protected":false},"author":6,"featured_media":42316,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[174],"tags":[],"class_list":["post-42296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puntate-2024-2025"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2025\/03\/massimi-1024x576.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/42296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/comments?post=42296"}],"version-history":[{"count":2,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/42296\/revisions"}],"predecessor-version":[{"id":42318,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/42296\/revisions\/42318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/media\/42316"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/media?parent=42296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/categories?post=42296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/tags?post=42296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}