{"id":37840,"date":"2024-11-26T21:09:49","date_gmt":"2024-11-26T20:09:49","guid":{"rendered":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/?p=37840"},"modified":"2024-11-26T21:09:49","modified_gmt":"2024-11-26T20:09:49","slug":"la-guerra-fallimento-dellumanita","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/2024\/11\/26\/la-guerra-fallimento-dellumanita\/","title":{"rendered":"La guerra: fallimento dell&#8217;umanit\u00e0"},"content":{"rendered":"<p>Puntata sulla pace ispirata alla figura di Ernesto Balducci, una delle personalit\u00e0 di maggior spicco nella cultura cattolica postconciliare, amico di Giorgio La Pira, David Maria Turoldo, Don Lorenzo Milani e tanti altri. Gennaro Ferrara ne parla con Grazia Bellini, presidente della Fondazione Ernesto Balducci e in collegamento con Franco Vaccari, fondatore e presidente di Rondine. Cittadella della Pace<\/p>\n<div class=\"rwd-video\"><iframe title=\"Play 2000\" src=\"https:\/\/www.play2000.it\/play\/episode\/10377?startAt=0&#038;backToUrl=%2Fdetail%2F13%3Fepisode_id%3D10377%26season_id%3D464\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"Puntata sulla pace ispirata alla figura di Ernesto Balducci, una delle personalit\u00e0 di maggior spicco nella cultura cattolica postconciliare, amico di Giorgio La Pira, David Maria Turoldo, Don Lorenzo Milani e tanti altri. Gennaro Ferrara ne parla con Grazia Bellini, presidente della Fondazione Ernesto Balducci e in collegamento con Franco Vaccari, fondatore e presidente di [&hellip;]","protected":false},"author":6,"featured_media":37844,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[174],"tags":[],"class_list":["post-37840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puntate-2024-2025"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2024\/11\/diario26-1024x576.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/37840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/comments?post=37840"}],"version-history":[{"count":2,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/37840\/revisions"}],"predecessor-version":[{"id":37849,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/37840\/revisions\/37849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/media\/37844"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/media?parent=37840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/categories?post=37840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/tags?post=37840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}