{"id":11235,"date":"2019-09-09T17:37:00","date_gmt":"2019-09-09T15:37:00","guid":{"rendered":"http:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/?p=11235"},"modified":"2019-09-12T16:05:05","modified_gmt":"2019-09-12T14:05:05","slug":"il-diario-di-papa-francesco-il-bilancio-del-viaggio-in-africa-mons-gallagher-giappone","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/2019\/09\/09\/il-diario-di-papa-francesco-il-bilancio-del-viaggio-in-africa-mons-gallagher-giappone\/","title":{"rendered":"Il diario di Papa Francesco: il bilancio del Viaggio in Africa, Mons. Gallagher, Giappone"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter wp-image-7861 size-large\" src=\"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2018\/09\/Foto-Papa-tappo-paesi-Baltici-1024x681.jpg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2018\/09\/Foto-Papa-tappo-paesi-Baltici-1024x681.jpg 1024w, https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2018\/09\/Foto-Papa-tappo-paesi-Baltici-300x200.jpg 300w, https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2018\/09\/Foto-Papa-tappo-paesi-Baltici-768x511.jpg 768w, https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2018\/09\/Foto-Papa-tappo-paesi-Baltici-41x27.jpg 41w, https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2018\/09\/Foto-Papa-tappo-paesi-Baltici-280x186.jpg 280w, https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2018\/09\/Foto-Papa-tappo-paesi-Baltici-650x433.jpg 650w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><strong>LUNEDI\u2019 9 SETTEMBRE&nbsp; -MAURITIUS: ULTIMA TAPPA DEL VIAGGIO DI PAPA FRANCESCO IN AFRICA<\/strong><\/p>\n<p>Il Diario apre la settimana raccontando l\u2019ultima tappa del viaggio apostolico di Papa Bergoglio in Africa con il focus sulle Mauritius.<\/p>\n<p>Le dirette del mattino e del pomeriggio studieranno ogni tematica relativa al viaggio del Santo Padre, con ospiti in studio, approfondimenti e collegamenti con la vaticanista Cristiana Caricato e gli inviati di Tg2000.<\/p>\n<p>La mattina: Antananarivo-Port Louis-Antananarivo; Santa Messa al Monumento di Maria Regina della Pace; Pranzo con i Vescovi della CEDOI nell\u2019Episcopio.<\/p>\n<p>&nbsp;<\/p>\n<p>Ospiti in studio: Sr. Elisa Kidan\u00e8 Missionaria Comboniana; Shaylee Devi Seebun originaria delle Mauritius; Luigi Accattoli vaticanista e scrittore.<\/p>\n<p>Il pomeriggio: Visita privata al Santuario di Pere Laval; incontro con l\u2019establishment politico e la Societ\u00e0 Civile delle Mauritius; Cerimonia di congedo all\u2019Aeroporto di Port Louis; Partenza in aereo per Antananarivo; Arrivo all\u2019Aeroporto di Antananarivo in Madagascar.<\/p>\n<p>Ospiti in studio:&nbsp; Jean-L\u00e9onard Touadi, scrittore e giornalista; Prof. Angelo Turco Ordinario Geografo Iulm; Shaylee Devi Seebun originaria delle Mauritius; Luis Badilla&nbsp; Direttore de Il Sismografo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>MARTEDI\u2019 10 SETTEMBRE \u2013&nbsp; AFRICA: PROSPETTIVE E FUTURO<\/strong><\/p>\n<p>Per tracciare un primo bilancio del viaggio del Santo Padre in Africa appena conclusosi, il Diario ospita in studio la missionaria comboniana Sr. Elisa Kidan\u00e9 e il giornalista e filosofo Filomeno Lopes.<\/p>\n<p>Suor Elisa&nbsp; nasce a Segheneiti in Eritrea. Giornalista, Suor Elisa ha prestato il suo servizio nella redazione della rivista Raggio, poi diventata Combonifem, di cui \u00e8 stata per un periodo direttrice.<\/p>\n<p>Nel 2009 ha partecipato al II Sinodo per l\u2019Africa celebrato a Roma .Ha pubblicato alcune raccolte di poesie: Ho visto la speranza danzare (1995); Fotocopia a colori (1999); Orme nel cuore del mondo (2004) e Parole Clandestine (2008) e infine AFRICA NOSTRA MADRE TERRA (2017).<\/p>\n<p>Filomeno Lopes redattore del programma portoghese della Radio Vaticana \u00e8 originario della Guinea Bissau. Licenza in teologia fondamentale e Dottorato in filosofia e comunicazione Sociale presso la Pontificia Universit\u00e0 Gregoriana di Roma, Lopes \u00e8 autore di diverse opere sulla filosofia e teologia africana, tra cui:\u201cE se l&#8217;Africa scomparisse dal Mappamondo? Una Riflessione filosofica\u201d &#8211; Armando Editore; \u201cDalla mediocrit\u00e0 all&#8217;eccellenza. Riflessione di un immigrante africano\u201d &#8211;&nbsp; Ed Sui; \u201cFilodram\u00e1tica: Os PALOP tra filosofia e crise de consciencia hist\u00f3rica\u201d-&nbsp; Ed. Pauline &#8211; Maputo 2018.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>MERCOLEDI\u2019 11 SETTEMBRE \u2013 CONFERENZA STAMPA VIAGGIO APOSTOLICO IN AFRICA<\/strong><\/p>\n<p>Con la vaticanista del Tg2000 Cristiana Caricato ripercorriamo i punti pi\u00f9 importanti della Conferenza Stampa sull\u2019aereo che ha riportato il Santo Padre a Roma nel viaggio di ritorno dall\u2019Africa .<\/p>\n<p>&nbsp;<\/p>\n<p><strong>GIOVEDI\u2019 12 SETTEMBRE&nbsp; &#8211; MONS. PAUL RICHARD GALLAGHER&nbsp; &#8211; SEGRETARIO PER I RAPPORTI CON GLI STATI DELLA SANTA SEDE<\/strong><\/p>\n<p>Incontro televisivo a tutto campo con Mons. Paul Richard Gallagher, Segretario per i Rapporti con gli Stati della Santa Sede. Nato a Liverpool in Gran Bretagna nel 1954, Mons. Gallagher \u00e8 stato ordinato sacerdote per l\u2019arcidiocesi di Liverpool il 31 luglio 1977. Laureato in diritto canonico, \u00e8 entrato nel servizio diplomatico della Santa Sede il 1\u00b0 maggio 1984. Ha prestato servizio nelle rappresentanze pontificie in Tanzania (1984-1988), in Uruguay (1988-1991), nelle Filippine (1991-1995) e presso la sezione per i Rapporti con gli Stati della Segreteria di Stato (1995-2000). Dal 15 luglio 2000 \u00e8 stato inviato speciale, osservatore permanente presso il Consiglio d\u2019Europa a Strasburgo. Il 22 gennaio 2004 \u00e8 stato eletto alla sede titolare di Hodelm, con dignit\u00e0 di arcivescovo, e nominato nunzio apostolico in Burundi. Ordinato vescovo il 13 marzo 2004, \u00e8 stato nunzio apostolico in Guatemala (2009-2012) e in Australia (2012-2014). Dal novembre 2014 \u00e8 Segretario per i Rapporti con gli Stati della Santa Sede.<\/p>\n<p><strong>VENERDI\u2019 13 SETTEMBRE \u2013 GIAPPONE: ATTESE E SPERANZE PER IL PROSSIMO VIAGGIO APOSTOLICO DEL SANTO PADRE<\/strong><\/p>\n<p>Conclude la settimana del Diario la presenza in studio di padre Andrea Lembo missionario del Pime in Giappone dal 2009. Ha esercitato il suo ministero in parrocchia presso la chiesa della Sacra Famiglia a Fuchu, nella periferia di Tokyo; ha creato nella megalopoli giapponese un centro culturale frequentato non solo da cristiani e dal 2017; \u00e8 responsabile della Comunit\u00e0 dei Missionari del Pime in Giappone. La sua profonda attenzione per i giovani l\u2019ha portato a fondare a Tokyo \u201cGalilea\u201d: una struttura articolata a loro dedicata.<\/p>\n","protected":false},"excerpt":{"rendered":"LUNEDI\u2019 9 SETTEMBRE&nbsp; -MAURITIUS: ULTIMA TAPPA DEL VIAGGIO DI PAPA FRANCESCO IN AFRICA Il Diario apre la settimana raccontando l\u2019ultima tappa del viaggio apostolico di Papa Bergoglio in Africa con il focus sulle Mauritius. Le dirette del mattino e del pomeriggio studieranno ogni tematica relativa al viaggio del Santo Padre, con ospiti in studio, approfondimenti [&hellip;]","protected":false},"author":9,"featured_media":7861,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[117],"tags":[],"class_list":["post-11235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2018\/09\/Foto-Papa-tappo-paesi-Baltici-1024x681.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/11235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/comments?post=11235"}],"version-history":[{"count":2,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/11235\/revisions"}],"predecessor-version":[{"id":11265,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/11235\/revisions\/11265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/media\/7861"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/media?parent=11235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/categories?post=11235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/tags?post=11235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}