{"id":11173,"date":"2019-08-29T15:40:43","date_gmt":"2019-08-29T13:40:43","guid":{"rendered":"http:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/?p=11173"},"modified":"2019-09-04T16:10:06","modified_gmt":"2019-09-04T14:10:06","slug":"il-diario-di-papa-francesco-viaggio-in-mozambico-madagascar-mauritius","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/2019\/08\/29\/il-diario-di-papa-francesco-viaggio-in-mozambico-madagascar-mauritius\/","title":{"rendered":"Il diario di Papa Francesco: Viaggio in Mozambico, Madagascar, Mauritius"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter wp-image-9900\" src=\"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2019\/04\/Papa-Francesco.jpg\" alt=\"\" width=\"640\" height=\"428\" srcset=\"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2019\/04\/Papa-Francesco.jpg 1000w, https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2019\/04\/Papa-Francesco-300x201.jpg 300w, https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2019\/04\/Papa-Francesco-768x514.jpg 768w, https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2019\/04\/Papa-Francesco-40x27.jpg 40w, https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2019\/04\/Papa-Francesco-280x187.jpg 280w, https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2019\/04\/Papa-Francesco-650x435.jpg 650w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><strong>LUNED\u00cc 2 SETTEMBRE\u2013 OPERE MISSIONARIE<\/strong><\/p>\n<p>In occasione del mese missionario straordinario che si vivr\u00e0 in Ottobre, la settimana del Diario apre con la presenza in studio di Mons. Giampietro Dal Toso, Arcivescovo Foraziana, segretario aggiunto della Congregazione per l&#8217;evangelizzazione dei popoli e Presidente delle Pontificie Opere Missionarie.<br \/>\nIl Vescovo Dal Toso approfondir\u00e0 la missione ad gentes. Nel 2019 infatti ricorrono i 100 anni dalla Lettera Apostolica Maximum Illud di Papa Benedetto XV. Per celebrare questa ricorrenza Papa Francesco ha indetto Ottobre 2019 il Mese Missionario Straordinario.<br \/>\nIl Santo Padre ha indicato questo tema: \u201cBattezzati e inviati: la Chiesa di Cristo in missione nel mondo\u201d. Risvegliare la consapevolezza della missio ad gentes e riprendere con nuovo slancio la responsabilit\u00e0 dell\u2019annuncio del Vangelo, accomunano la sollecitudine pastorale di Papa Benedetto XV nella Maximum Illud e la vitalit\u00e0 missionaria espressa da Papa Francesco nell\u2019Esortazione Apostolica Evangelii Gaudium: \u00abL\u2019azione missionaria \u00e8 il paradigma di ogni opera della Chiesa\u00bb (EG 15).<\/p>\n<p><strong>MARTED\u00cc 3 SETTEMBRE \u2013 AVVICINAMENTO AL CONTINENTE NERO<\/strong><br \/>\nPer cominciare a tracciare uno scenario del nuovo viaggio apostolico di Papa Francesco in Africa, il Diario ospita padre Toma\u017e Mavri\u010d C.M. Superiore Generale della Congregazione della Missione e delle Figlie della Carit\u00e0, 24\u00b0 successore di San Vincenzo de\u2019 Paoli .<br \/>\nSar\u00e0 interessante sentire dal Vincenziano padre Mavri\u010d tutti i punti di raccordo che legano la sua Congregazione alla \u201cmissionarit\u00e0\u201d in Mozambico, Madagascar e Mauritius.<\/p>\n<p>___________________________________________________________________________<br \/>\nDA MERCOLEDI\u2019 4 SETTEMBRE AL 10 SETTEMBRE: PAPA FRANCESCO IN AFRICA PER VISITARE MOZAMBICO, MADAGASCAR, MAURITIUS.<br \/>\nIL DIARIO CON LE DIRETTE QUOTIDIANE STUDIA OGNI TEMATICA RELATIVA AL VIAGGIO DEL SANTO PADRE CON OSPITI IN STUDIO, APPROFONDIMENTI E COLLEGAMENTI CON LA VATICANISTA CRISTIANA CARICATO E GLI INVIATI DI TG2000.<\/p>\n<p>_______________________________________________________________<\/p>\n<p><strong>MERCOLEDI\u2019 4 SETTEMBRE \u2013 PAPA FRANCESCO IN VOLO VERSO L\u2019AFRICA<\/strong><br \/>\nLuca Mainoldi, responsabile Desk Africa dell\u2019Agenzia Fides ci aiuter\u00e0 a vivere l\u2019emozione di questo nuovo viaggio del Santo Padre in Africa ed a individuare gli accadimenti che vedremo realizzarsi durante la permanenza del Papa in Mozambico, Madagascar, Mauritius.<\/p>\n<p>______________________________________________________________________<\/p>\n<p><strong>GIOVEDI\u2019 5 SETTEMBRE &#8211; 1\u00b0 GIORNO MOZAMBICO<\/strong><br \/>\nLa mattina del 5 settembre apertura con l\u2019establishment politico e la Societ\u00e0 Civile del Mozambico poi lo svolgersi dell\u2019incontro interreligioso con i Giovani.<\/p>\n<p>Ospiti in studio:<br \/>\nMario Giro della Comunit\u00e0 di Sant\u2019Egidio; Luis Badilla Direttore de Il Sismografo; padre Fabio Malesa Missionario della Consolata; Padre Ev\u00f3dio Jo\u00e3o dell\u2019Ordine dei Frati Minori e originario del Mozambico.<\/p>\n<p>Il pomeriggio seguiamo l\u2019Incontro con i Vescovi, con i Sacerdoti, Religiosi\/e, Consacrati e Seminaristi, Catechisti e Animatori nella Cattedrale dell\u2019Immacolata Concezione.<\/p>\n<p>Ospiti in studio:<br \/>\npadre Agostino Augusto dei Frati Minori Cappuccini, originario del Mozambico; il Prof. Roberto Rusconi Storico del Cristianesimo; Anna Pozzi giornalista di \u201cMondo e Missione\u201d;&nbsp;SALVATORE CERNUZIO \u2013 VATICAN INSIDER<\/p>\n<p>______________________________________________________________<\/p>\n<p><strong>VENERDI 6 SETTEMBRE &#8211; 2 \u00b0 GIORNO MOZAMBICO<br \/>\n<\/strong><br \/>\nLa mattina Visita all&#8217;Ospedale di Zimpeto; Santa Messa nello Stadio di Zimpeto; Cerimonia di congedo all\u2019Aeroporto di Maputo; Partenza dell\u2019Aereo Papale per Antananarivo.<\/p>\n<p>Ospiti in studio: Don Dante Carraro Direttore \u201cMedici Con L\u2019africa Cuamm\u201d; Marco Impagliazzo Presidente della Comunit\u00e0 di Sant\u2019Egidio; Suor Dalmazia Colombo Missionaria della Consolata; Filomeno Lopes giornalista di Radio Vaticana.<\/p>\n<p>Il pomeriggio: primo contrappunto del viaggio con il vaticanista e scrittore Luigi Accattoli.<\/p>\n<p>_____________________________________________<\/p>\n<p><strong>SABATO 7 SETTEMBRE 1\u00b0 GIORNO MADAGASCAR<br \/>\n<\/strong><br \/>\nLa mattina: Antananarivo, Visita di cortesia al Presidente nel Palazzo Presidenziale \u201cIavoloha\u201d; Incontro con le Autorit\u00e0, la Societ\u00e0 civile e il Corpo Diplomatico nel Ceremony Building; Ora Media nel Monastero delle Carmelitane Scalze.<\/p>\n<p>Ospiti in studio: Padre Cesare Giraudo Gesuita, Padre Norbert Solondrazana dell\u2019Ordine dei Frati Minori Cappuccini originario del Madagascar; Sr. Marisa Bordiga Segretaria Generale delle Suore Carmelitane di Santa Teresa di Torino; Vincenzo Bonomo Rettore della Pontificia Universit\u00e0 Lateranense.<\/p>\n<p>Il pomeriggio: Incontro con i Vescovi del Madagascar nella Cattedrale di Andohalo; Visita alla tomba della Beata Victoire Rasoamanarivo; Veglia con i Giovani nel Campo Diocesano di Soamandrakizay.<\/p>\n<p>Ospiti in studio : padre Cesare Giraudo Gesuita; Sr. Christine Razafiarisoa delle Suore Carmelitane di Santa Teresa di Torino originaria del Madagascar; Michela Marchetto gi\u00e0 fidei donum in Madagascar; Enrico Casale Responsabile News Sito Rivista Africa dei Padri Bianchi.<\/p>\n<p>______________________________________________________<\/p>\n<p><strong>DOMENICA 8 SETTEMBRE &#8211; 2 \u00b0 GIORNO MADAGASCAR<\/strong><\/p>\n<p>La mattina: Antananarivo: Santa Messa nel Campo Diocesano di Soamandrakizay; Pranzo con Il Seguito Papale in Nunziatura.<br \/>\nOspiti in studio: Sr. Hanitriniaina Marie Meltine Ranomenjanahary delle Suore Orsoline di Verona originaria del Madagascar; padre Efrem Tresoldi Missionario Comboniano, Direttore di Nigrizia.<\/p>\n<p>Il pomeriggio: Visita alla Citt\u00e0 dell&#8217;Amicizia di Akamasoa; Preghiera per i Lavoratori nel Cantiere di Mahatzana; Incontro con i Sacerdoti, Religiosi\/e, Consacrati e Seminaristi nel Coll\u00e8ge de Saint Michel.<\/p>\n<p>Ospiti in studio: Don Emanuele Benatti gi\u00e0 Fidei Donum in Madagascar; Prof. Leonardo Lucarini Medico Chirurgo missionario in Madagascar; Fabio Carminati Responsabile Pagina Esteri Avvenire; Sr. Solange Ranaivoson delle Suore di San Giuseppe di Aosta, originaria del Madagascar.<br \/>\n__________________________________________<\/p>\n<p><strong>LUNEDI\u2019 9 SETTEMBRE -MAURITIUS<\/strong><\/p>\n<p>La mattina: Antananarivo-Port Louis-Antananarivo; Santa Messa al Monumento di Maria Regina della Pace; Pranzo con i Vescovi della CEDOI nell\u2019Episcopio.<\/p>\n<p>Ospiti in studio: Sr. Elisa Kidan\u00e8 Missionaria Comboniana; Shaylee Devi Seebun originaria delle Mauritius; Luigi Accattoli vaticanista e scrittore.<\/p>\n<p>Il pomeriggio: Visita privata al Santuario di Pere Laval; incontro con l\u2019establishment politico e la Societ\u00e0 Civile delle Mauritius; Cerimonia di congedo all\u2019Aeroporto di Port Louis; Partenza in aereo per Antananarivo; Arrivo all\u2019Aeroporto di Antananarivo in Madagascar.<\/p>\n<p>Ospiti in studio: Jean-L\u00e9onard Touadi, scrittore e giornalista; Prof. Angelo Turco Ordinario Geografo Iulm; Shaylee Devi Seebun originaria delle Mauritius; Luis Badilla Direttore de Il Sismografo.<\/p>\n","protected":false},"excerpt":{"rendered":"LUNED\u00cc 2 SETTEMBRE\u2013 OPERE MISSIONARIE In occasione del mese missionario straordinario che si vivr\u00e0 in Ottobre, la settimana del Diario apre con la presenza in studio di Mons. Giampietro Dal Toso, Arcivescovo Foraziana, segretario aggiunto della Congregazione per l&#8217;evangelizzazione dei popoli e Presidente delle Pontificie Opere Missionarie. Il Vescovo Dal Toso approfondir\u00e0 la missione ad [&hellip;]","protected":false},"author":9,"featured_media":9900,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[117],"tags":[],"class_list":["post-11173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-content\/uploads\/sites\/20\/2019\/04\/Papa-Francesco.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/11173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/comments?post=11173"}],"version-history":[{"count":4,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/11173\/revisions"}],"predecessor-version":[{"id":11194,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/posts\/11173\/revisions\/11194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/media\/9900"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/media?parent=11173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/categories?post=11173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/ildiariodipapafrancesco\/wp-json\/wp\/v2\/tags?post=11173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}