{"id":43,"date":"2019-03-27T15:21:19","date_gmt":"2019-03-27T14:21:19","guid":{"rendered":"http:\/\/staging.tv2000.it\/europeforus\/?post_type=video&#038;p=43"},"modified":"2019-03-28T15:17:54","modified_gmt":"2019-03-28T14:17:54","slug":"dal-2021-stop-allora-legale-parlamento-ue-approva","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/europeforus\/video\/dal-2021-stop-allora-legale-parlamento-ue-approva\/","title":{"rendered":"Dal 2021 stop all\u2019ora legale. Parlamento Ue dice s\u00ec alla proposta"},"content":{"rendered":"<p>Il Parlamento europeo oggi ha deciso anche di abolire il cambio dell&#8217;ora legale, ma solo nel 2021. Il servizio di Clara Iatosti<\/p>\n","protected":false},"featured_media":46,"comment_status":"open","ping_status":"closed","template":"","tags":[],"class_list":["post-43","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-news"],"acf":[],"aioseo_notices":[],"url_youtube":"nVD7Rw73_R4","featured_image_url":"https:\/\/i.ytimg.com\/vi\/nVD7Rw73_R4\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/europeforus\/wp-json\/wp\/v2\/video\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/europeforus\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/europeforus\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/europeforus\/wp-json\/wp\/v2\/comments?post=43"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/europeforus\/wp-json\/wp\/v2\/media\/46"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/europeforus\/wp-json\/wp\/v2\/media?parent=43"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/europeforus\/wp-json\/wp\/v2\/tags?post=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}