{"id":9596,"date":"2024-02-20T10:51:14","date_gmt":"2024-02-20T09:51:14","guid":{"rendered":"http:\/\/staging.tv2000.it\/docfilm\/?p=9596"},"modified":"2024-02-20T11:17:14","modified_gmt":"2024-02-20T10:17:14","slug":"il-dono-della-luna-futuri-non-scritti-la-sconfitta-della-mafia","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2024\/02\/20\/il-dono-della-luna-futuri-non-scritti-la-sconfitta-della-mafia\/","title":{"rendered":"Il dono della luna, futuri non scritti- la sconfitta della mafia"},"content":{"rendered":"<p><strong> <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2020\/03\/ildonodellaluna_ita.jpg\"><img decoding=\"async\" class=\" wp-image-9606 alignleft\" src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2020\/03\/ildonodellaluna_ita-727x1024.jpg\" alt=\"\" width=\"500\" height=\"704\" srcset=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2020\/03\/ildonodellaluna_ita-727x1024.jpg 727w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2020\/03\/ildonodellaluna_ita-213x300.jpg 213w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2020\/03\/ildonodellaluna_ita-768x1082.jpg 768w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2020\/03\/ildonodellaluna_ita-19x27.jpg 19w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2020\/03\/ildonodellaluna_ita-280x395.jpg 280w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2020\/03\/ildonodellaluna_ita-650x916.jpg 650w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/strong><em>Il dono della luna, <\/em>un documentario prodotto da Tv2000factory,&nbsp; di Gianni Vukaj e Beatrice Bernacchi.<\/p>\n<p>Tre storie che prendono forma attraverso la voce di Antonio, un bambino palermitano che ama gli eroi, le storie epiche dei cavalieri e le loro gesta, colleziona Pupi e cita a memoria l\u2019Orlando Furioso. E\u2019 lui il nostro cantastorie che ci introduce nella vita quotidiana di tre famiglie italiane ferite per mano della mafia. Le vittime non sono solo i morti, ma sono tutti coloro che hanno dovuto convivere con compleanni non festeggiati, abbracci non ricevuti e baci della buonanotte non dati. Combattere la mafia \u00e8 anche questo: ricordare i propri cari onorandoli con la propria vita, volgendo ogni tanto uno sguardo alla Luna, l\u00e0 dove si conservano le cose pi\u00f9 preziose.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"Il dono della luna, un documentario prodotto da Tv2000factory,&nbsp; di Gianni Vukaj e Beatrice Bernacchi. Tre storie che prendono forma attraverso la voce di Antonio, un bambino palermitano che ama gli eroi, le storie epiche dei cavalieri e le loro gesta, colleziona Pupi e cita a memoria l\u2019Orlando Furioso. E\u2019 lui il nostro cantastorie che [&hellip;]","protected":false},"author":35,"featured_media":9599,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-9596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2020\/03\/Pupi-siciliani-il-dono-della-luna-tv2000-doc-mafia-7-1024x1024.png","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/9596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=9596"}],"version-history":[{"count":7,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/9596\/revisions"}],"predecessor-version":[{"id":142657,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/9596\/revisions\/142657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/9599"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=9596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=9596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=9596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}