{"id":9270,"date":"2019-12-30T15:36:19","date_gmt":"2019-12-30T14:36:19","guid":{"rendered":"http:\/\/staging.tv2000.it\/docfilm\/?p=9270"},"modified":"2019-12-30T15:36:58","modified_gmt":"2019-12-30T14:36:58","slug":"la-marcia-dei-pinguini","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2019\/12\/30\/la-marcia-dei-pinguini\/","title":{"rendered":"La marcia dei pinguini"},"content":{"rendered":"<p><b><a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/la-marcia-dei-pinguini-20.jpg\"><img decoding=\"async\" class=\"size-full wp-image-9277 alignleft\" src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/la-marcia-dei-pinguini-20.jpg\" alt=\"\" width=\"816\" height=\"590\" srcset=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/la-marcia-dei-pinguini-20.jpg 816w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/la-marcia-dei-pinguini-20-300x217.jpg 300w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/la-marcia-dei-pinguini-20-768x555.jpg 768w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/la-marcia-dei-pinguini-20-37x27.jpg 37w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/la-marcia-dei-pinguini-20-280x202.jpg 280w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/la-marcia-dei-pinguini-20-650x470.jpg 650w\" sizes=\"(max-width: 816px) 100vw, 816px\" \/><\/a>Gioved\u00ec 2 gennaio alle 21.20<\/b><i><b> &#8211;<\/b> La marcia dei pinguini<\/i>&nbsp;(<i>La Marche de l&#8217;empereur<\/i>) \u00e8 un&nbsp;documentario&nbsp;del&nbsp;2005&nbsp;diretto da&nbsp;Luc Jacquet.<\/p>\n<p><em>Trama<\/em><\/p>\n<p>Il&nbsp;pinguino imperatore, un uccello che vive nelle regioni antartiche, deve migrare per diversi mesi in determinate zone per riprodursi e allevare i propri figli.&nbsp;<i>La marcia dei pinguini<\/i>&nbsp;segue da vicino il viaggio di una colonia e successivamente una coppia di pinguini che affronta diverse marce affinch\u00e9 il piccolo possa resistere al freddo e alla fame nel periodo dopo la sua nascita. Il film mostra le sofferenze dei pinguini durante la loro riproduzione, partendo dalla marcia che, al sopraggiungere dell&#8217;inverno, li porta dall&#8217;oceano all&#8217;interno della regione ghiacciata. Qui si formano le coppie che si riproducono, con la femmina che depone un uovo. Alcuni piccoli muoiono ancora nell&#8217;uovo, e ci\u00f2 avviene quando la femmina, al momento di tornare all&#8217;oceano per prendere cibo per il piccolo, deve passare l&#8217;uovo al compagno; se sbaglia qualche passo della danza, l&#8217;uovo cade nel ghiaccio e si congela. A questo punto il padre cova l&#8217;uovo, mentre la madre torna all&#8217;oceano. Di ritorno, la femmina trova il giovane pinguino gi\u00e0 nato (se sopravvissuto al freddo invernale) e lo nutre, mentre il padre deve tornare all&#8217;oceano per sfamarsi, dopo mesi di digiuno al gelo. Al ritorno, ormai in estate, trova la famiglia ad attenderlo, e prima di separarsi promette alla compagna che cercher\u00e0 di ricongiungersi con lei l&#8217;inverno successivo, dopodich\u00e9 tutti si separano e fanno la loro ultima marcia annuale di ritorno all&#8217;oceano ognuno per conto proprio, con gli adulti che ripeteranno le marce l&#8217;anno successivo, mentre i piccoli rimangono in mare per circa quattro anni, durante i quali non \u00e8 chiaro dove vadano e cosa facciano, per poi ricomparire all&#8217;interno dei gruppi che prendono parte alle marce una volta diventati adulti.<\/p>\n<p>Nei vari passaggi, inevitabilmente qualche esemplare soccombe a causa del grande freddo, della fame . Altri esemplari si perdono, rimangono indietro o non riescono ad accoppiarsi: considerato che la vita dei pinguini \u00e8 una vita di gruppo, i pinguini rimasti soli sono destinati a morire congelati.<\/p>\n","protected":false},"excerpt":{"rendered":"Gioved\u00ec 2 gennaio alle 21.20 &#8211; La marcia dei pinguini&nbsp;(La Marche de l&#8217;empereur) \u00e8 un&nbsp;documentario&nbsp;del&nbsp;2005&nbsp;diretto da&nbsp;Luc Jacquet. Trama Il&nbsp;pinguino imperatore, un uccello che vive nelle regioni antartiche, deve migrare per diversi mesi in determinate zone per riprodursi e allevare i propri figli.&nbsp;La marcia dei pinguini&nbsp;segue da vicino il viaggio di una colonia e successivamente una [&hellip;]","protected":false},"author":35,"featured_media":9277,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-9270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/la-marcia-dei-pinguini-20.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/9270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=9270"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/9270\/revisions"}],"predecessor-version":[{"id":9278,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/9270\/revisions\/9278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/9277"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=9270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=9270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=9270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}