{"id":9246,"date":"2022-08-10T12:00:08","date_gmt":"2022-08-10T10:00:08","guid":{"rendered":"http:\/\/staging.tv2000.it\/docfilm\/?p=9246"},"modified":"2022-07-25T11:37:36","modified_gmt":"2022-07-25T09:37:36","slug":"michelangelo-e-la-sistina","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2022\/08\/10\/michelangelo-e-la-sistina\/","title":{"rendered":"Michelangelo e la sistina"},"content":{"rendered":"<p><strong><a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/4378815511_9f78037ec7_b.jpg\"><img decoding=\"async\" class=\"size-large wp-image-9247 alignleft\" src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/4378815511_9f78037ec7_b-1024x683.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/4378815511_9f78037ec7_b.jpg 1024w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/4378815511_9f78037ec7_b-300x200.jpg 300w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/4378815511_9f78037ec7_b-768x512.jpg 768w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/4378815511_9f78037ec7_b-40x27.jpg 40w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/4378815511_9f78037ec7_b-280x187.jpg 280w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/4378815511_9f78037ec7_b-650x434.jpg 650w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>Marted\u00ec 23 agosto in seconda serata su Tv2000<\/strong> &#8211;&nbsp;<em>Michelangelo e la sistina <\/em>un documentario di Piero Badaloni e Nino Criscenti.&nbsp;<\/p>\n<p>Il 31 ottobre del 1512, Michelangelo finisce di dipingere la volta della Cappella Sistina, smonta il ponteggio su cui ha lavorato per quattro anni e apre la porta a papa Giulio II. Una novit\u00e0 assoluta, che cambia per sempre il corso della storia dell\u2019arte.<\/p>\n<p>Perch\u00e9 Michelangelo, che era a Roma per scolpire la tomba del papa, viene invece incaricato di affrescare la volta, lui che pittore non \u00e8? Chi convince Giulio II a cambiare idea, mettendo il giovane artista fiorentino di fronte a una sfida? Come riesce Michelangelo a realizzare un capolavoro che ancora oggi richiama milioni di turisti da tutto il mondo?<\/p>\n<p>Il documentario ricostruisce la storia dell\u2019opera anche attraverso documenti originali conservati negli archivi di mezzo mondo. Ad accompagnare questo viaggio nella pittura le voci di Antonio Paolucci, ex-direttore dei musei vaticani, di Massimo Firpo, grande storico del \u2018500, di Gianluigi Colalucci, restauratore della Sistina e dello storico dell\u2019arte Eugenio Riccomini. Franco Nero legge le lettere di Michelangelo.<\/p>\n","protected":false},"excerpt":{"rendered":"Marted\u00ec 23 agosto in seconda serata su Tv2000 &#8211;&nbsp;Michelangelo e la sistina un documentario di Piero Badaloni e Nino Criscenti.&nbsp; Il 31 ottobre del 1512, Michelangelo finisce di dipingere la volta della Cappella Sistina, smonta il ponteggio su cui ha lavorato per quattro anni e apre la porta a papa Giulio II. Una novit\u00e0 assoluta, [&hellip;]","protected":false},"author":35,"featured_media":9247,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-9246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/12\/4378815511_9f78037ec7_b-1024x683.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/9246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=9246"}],"version-history":[{"count":2,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/9246\/revisions"}],"predecessor-version":[{"id":13369,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/9246\/revisions\/13369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/9247"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=9246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=9246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=9246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}