{"id":8322,"date":"2020-04-14T10:47:29","date_gmt":"2020-04-14T08:47:29","guid":{"rendered":"http:\/\/staging.tv2000.it\/docfilm\/?p=8322"},"modified":"2020-04-14T11:03:01","modified_gmt":"2020-04-14T09:03:01","slug":"la-casa-nella-prateria-di-laura-ingalls-wilder","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2020\/04\/14\/la-casa-nella-prateria-di-laura-ingalls-wilder\/","title":{"rendered":"La casa nella prateria di Laura Ingalls Wilder"},"content":{"rendered":"<p><strong><a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/05\/LITTLEHOUSE_GAL_15_L.jpg\"><img decoding=\"async\" class=\"size-large wp-image-8326 alignleft\" src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/05\/LITTLEHOUSE_GAL_15_L-683x1024.jpg\" alt=\"\" width=\"640\" height=\"960\" srcset=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/05\/LITTLEHOUSE_GAL_15_L-683x1024.jpg 683w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/05\/LITTLEHOUSE_GAL_15_L-200x300.jpg 200w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/05\/LITTLEHOUSE_GAL_15_L-768x1152.jpg 768w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/05\/LITTLEHOUSE_GAL_15_L-18x27.jpg 18w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/05\/LITTLEHOUSE_GAL_15_L-280x420.jpg 280w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/05\/LITTLEHOUSE_GAL_15_L-650x975.jpg 650w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/05\/LITTLEHOUSE_GAL_15_L.jpg 2000w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>Da luned\u00ec 20 aprile, ogni giorno, alle 12.50 &#8211;&nbsp; La casa nella prateria di Laura Ingalls Wilder&nbsp;<\/strong><\/p>\n<p>La serie racconta le avventure di una famiglia di pionieri in Kansas agli inizi del secolo scorso. Gli episodi sono tratti dalla raccolta autobiografica per ragazzi \u2018La piccola casa nella prateria\u2019 (Little House on the Prairie) della scrittrice statunitense Laura Ingalls Wilder.&#8221;&nbsp;<strong>&nbsp;<\/strong><\/p>\n<p><strong>Gli attori<\/strong><\/p>\n<p>Cameron Bancroft nei panni di Charles Ingalls (Pa), Erin Cottrell nei panni di Caroline Ingalls (Ma), Kyle Chavarria nei panni di Laura Ingalls e Danielle Ryan Chuchran nei panni di Mary Ingalls.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Curiosit\u00e0<\/strong><\/p>\n<p>Per \u2018La piccola casa nella prateria\u2019 sono stati impiegati quattro mesi di riprese, ed \u00e8 stata girata in una zona incontaminata nei pressi della citt\u00e0 di Calgary (Canada). L&#8217;epica produzione riprende la portata e l&#8217;ampiezza della frontiera e ricrea la saga letteraria con accuratezza minuziosa.<\/p>\n<p>Guest star sono Gregory Sporlader nei panni di Mr. Edwards, Gina Stockdale nei panni di Mrs. Scott, Dorian Harewood nei panni di Dr. Tan, James Cosmo nei panni di Mr. Scott e Gina Stockdale nei panni di Mrs. Scott e Byron Chief-Moon nei panni di Soldat du Chene.<\/p>\n","protected":false},"excerpt":{"rendered":"Da luned\u00ec 20 aprile, ogni giorno, alle 12.50 &#8211;&nbsp; La casa nella prateria di Laura Ingalls Wilder&nbsp; La serie racconta le avventure di una famiglia di pionieri in Kansas agli inizi del secolo scorso. Gli episodi sono tratti dalla raccolta autobiografica per ragazzi \u2018La piccola casa nella prateria\u2019 (Little House on the Prairie) della scrittrice [&hellip;]","protected":false},"author":35,"featured_media":8323,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-8322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-serie-tv"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/05\/LITTLEHOUSE_GAL_11_L-e1559314040265-981x1024.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/8322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=8322"}],"version-history":[{"count":4,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/8322\/revisions"}],"predecessor-version":[{"id":9811,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/8322\/revisions\/9811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/8323"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=8322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=8322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=8322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}