{"id":7990,"date":"2019-03-11T13:09:03","date_gmt":"2019-03-11T12:09:03","guid":{"rendered":"http:\/\/staging.tv2000.it\/docfilm\/?p=7990"},"modified":"2019-03-11T13:09:03","modified_gmt":"2019-03-11T12:09:03","slug":"don-peppe-diana-il-martire-del-riscatto","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2019\/03\/11\/don-peppe-diana-il-martire-del-riscatto\/","title":{"rendered":"Don Peppe Diana, il martire del riscatto"},"content":{"rendered":"<p><strong>Luned\u00ec 18 marzo alle 22.45 su Tv2000 &#8211;<\/strong><em> Don Peppe Diana, il martire del riscatto<\/em> di Luigi Ferraiuolo in onda la&nbsp;vigilia del 25\u00b0 anniversario della morte del sacerdote di Casal di Principe ucciso dalla camorra il 19 marzo 1994 in chiesa, nel giorno del suo onomastico.<\/p>\n<p>Nel documentario le interviste agli amici pi\u00f9 cari e ai parenti: dal sindaco di Casal di principe di allora e oggi Renato Natale, alla madre Iolanda Di Tella, dai giornalisti Raffaele Sardo e Nicola Alfiero, che firmarono con don Diana alcuni documenti contro i clan. Tra le testimonianze pi\u00f9 significative quelle del suo confessore, don Clemente Petrillo, e di colui che si pu\u00f2 definire il \u2018padre spirituale\u2019, insieme con don Tonino Bello: il vescovo emerito di Caserta e Sessa Aurunca, mons. Raffaele Nogaro. E poi il ricordo del giudice Raffaele Cantone della stessa diocesi di don Diana, la diocesi di Aversa. Il documentario di Tv2000 \u00e8 aperto da Augusto Di Meo, il testimone oculare. Nel lungometraggio anche le testimonianze di chi non \u00e8 andato via e ha \u2018resistito\u2019 alla camorra.<\/p>\n<p style=\"text-align: center;\"><strong>Trailer:<\/strong><\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"Don Peppe Diana: su Tv2000 il docufilm sul sacerdote ucciso dalla camorra\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/MsEUoBI_BwI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"Luned\u00ec 18 marzo alle 22.45 su Tv2000 &#8211; Don Peppe Diana, il martire del riscatto di Luigi Ferraiuolo in onda la&nbsp;vigilia del 25\u00b0 anniversario della morte del sacerdote di Casal di Principe ucciso dalla camorra il 19 marzo 1994 in chiesa, nel giorno del suo onomastico. Nel documentario le interviste agli amici pi\u00f9 cari e [&hellip;]","protected":false},"author":35,"featured_media":7991,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-7990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2019\/03\/diana-peppe-don-rai-e1552306127854.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/7990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=7990"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/7990\/revisions"}],"predecessor-version":[{"id":7992,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/7990\/revisions\/7992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/7991"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=7990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=7990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=7990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}