{"id":6146,"date":"2018-06-25T12:55:38","date_gmt":"2018-06-25T10:55:38","guid":{"rendered":"http:\/\/staging.tv2000.it\/docfilm\/?p=6146"},"modified":"2018-06-25T15:43:32","modified_gmt":"2018-06-25T13:43:32","slug":"la-giostra-del-saracino-edizione-in-notturna-della-136a-edizione","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2018\/06\/25\/la-giostra-del-saracino-edizione-in-notturna-della-136a-edizione\/","title":{"rendered":"La giostra del saracino, in notturna"},"content":{"rendered":"<p style=\"text-align: left;\"><a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/giostra.jpg\"><img decoding=\"async\" class=\"size-large wp-image-6147 alignleft\" src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/giostra-1024x576.jpg\" alt=\"\" width=\"640\" height=\"360\" srcset=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/giostra-1024x576.jpg 1024w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/giostra-300x169.jpg 300w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/giostra-768x432.jpg 768w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/giostra-48x27.jpg 48w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/giostra-280x158.jpg 280w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/giostra-650x366.jpg 650w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/giostra.jpg 1600w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><strong>Domenica 1 luglio seconda serata su Tv2000 &#8211;<\/strong>\u00a0 Edizione in notturna della Giostra del Saracino di Arezzo, giunta alle 136a edizione: Mario Placidini e Gianfrancesco Chiericoni, storico Araldo della Giostra del Saracino, dalla suggestiva Piazza Grande di Arezzo, raccontano la sfida tra i quattro quartieri antichi impegnati nella conquista dell\u2019agognata \u201cLancia d\u2019oro\u201d dedicata quest\u2019anno alla Fiera Antiquaria nel cinquantesimo dalla prima edizione.<\/p>\n<p style=\"text-align: left;\">Post-produzione di Gianni Vukaj.<\/p>\n","protected":false},"excerpt":{"rendered":"Domenica 1 luglio seconda serata su Tv2000 &#8211;\u00a0 Edizione in notturna della Giostra del Saracino di Arezzo, giunta alle 136a edizione: Mario Placidini e Gianfrancesco Chiericoni, storico Araldo della Giostra del Saracino, dalla suggestiva Piazza Grande di Arezzo, raccontano la sfida tra i quattro quartieri antichi impegnati nella conquista dell\u2019agognata \u201cLancia d\u2019oro\u201d dedicata quest\u2019anno alla [&hellip;]","protected":false},"author":35,"featured_media":6147,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-6146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/giostra-1024x576.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/6146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=6146"}],"version-history":[{"count":2,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/6146\/revisions"}],"predecessor-version":[{"id":6160,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/6146\/revisions\/6160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/6147"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=6146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=6146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=6146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}