{"id":6141,"date":"2018-06-25T12:45:32","date_gmt":"2018-06-25T10:45:32","guid":{"rendered":"http:\/\/staging.tv2000.it\/docfilm\/?p=6141"},"modified":"2018-06-25T15:44:15","modified_gmt":"2018-06-25T13:44:15","slug":"mexico-tra-record-di-violenza-e-di-bellezza","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2018\/06\/25\/mexico-tra-record-di-violenza-e-di-bellezza\/","title":{"rendered":"Mexico, tra record di violenza e di bellezza (video)"},"content":{"rendered":"<p><strong><a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/mexicooo.png\"><img decoding=\"async\" class=\" wp-image-6142 alignleft\" src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/mexicooo.png\" alt=\"\" width=\"896\" height=\"414\" srcset=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/mexicooo.png 1000w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/mexicooo-300x139.png 300w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/mexicooo-768x355.png 768w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/mexicooo-58x27.png 58w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/mexicooo-280x129.png 280w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/mexicooo-650x300.png 650w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a>Sabato 30 giugno alle 23.35 su Tv2000 &#8211; <\/strong><em>Mexico, tra record di violenza e di bellezza <\/em>\u00e8 un reportage dal Messico, per un&#8217;immersione nella complessit\u00e0 di un paese dove la violenza \u00e8 drammaticamente paragonabile allo scenario di guerra in Siria, ma che resta meta preferita di 35 milioni di turisti ogni anno.\u00a0 Il Messico \u00e8 America Latina ma \u00e8 in America del Nord ed \u00e8 il cuore delle pi\u00f9 antiche civilt\u00e0 della Mesoamerica. Il suo territorio, di due milioni di chilometri quadrati e quasi 130 milioni di abitanti, sollecita ad andare oltre la banalit\u00e0 di una facile delineazione geografica e di un semplice\u00a0 inquadramento concettuale. Merita uno sguardo, dal di dentro, alla societ\u00e0 messicana, che affonda molto pi\u00f9 profondamente di altre nella storia \u2013 ci sono tracce di insediamenti umani di 11.000 anni avanti Cristo \u2013 e abbraccia con slancio potente ma intermittente la modernit\u00e0: Citt\u00e0 del Messico nel 2018 \u00e8 capitale mondiale del design.\u00a0 Una sfida appassionante\u00a0 tra \u201cRecord di violenza e di Bellezza\u201d.<\/p>\n<p style=\"text-align: center;\"><strong>TRAILER<\/strong><\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"&quot;Mexico&quot; sabato 30 giugno in seconda serata su Tv2000\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/gB7mUi_37Cw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"Sabato 30 giugno alle 23.35 su Tv2000 &#8211; Mexico, tra record di violenza e di bellezza \u00e8 un reportage dal Messico, per un&#8217;immersione nella complessit\u00e0 di un paese dove la violenza \u00e8 drammaticamente paragonabile allo scenario di guerra in Siria, ma che resta meta preferita di 35 milioni di turisti ogni anno.\u00a0 Il Messico \u00e8 [&hellip;]","protected":false},"author":35,"featured_media":6142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-6141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/06\/mexicooo.png","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/6141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=6141"}],"version-history":[{"count":3,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/6141\/revisions"}],"predecessor-version":[{"id":6161,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/6141\/revisions\/6161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/6142"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=6141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=6141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=6141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}