{"id":4753,"date":"2018-06-11T12:00:22","date_gmt":"2018-06-11T10:00:22","guid":{"rendered":"http:\/\/staging.tv2000.it\/docfilm\/?p=4753"},"modified":"2018-06-11T12:18:56","modified_gmt":"2018-06-11T10:18:56","slug":"chi-e-dayani-cristalcon-gael-garcia-bernal","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2018\/06\/11\/chi-e-dayani-cristalcon-gael-garcia-bernal\/","title":{"rendered":"&#8220;Chi \u00e8 Dayani Cristal?&#8221;con Gael Garcia Bernal"},"content":{"rendered":"<p><a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/01\/Chi-\u00e8-Dayani-Cristal1.jpg\"><img decoding=\"async\" class=\"size-full wp-image-4754 alignleft\" src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/01\/Chi-\u00e8-Dayani-Cristal1.jpg\" alt=\"\" width=\"900\" height=\"506\" \/><\/a><strong>Luned\u00ec 18 giugno alle 22.50 su Tv2000<\/strong> &#8211;\u00a0\u00a0<i><b>Chi \u00e8 Dayani Cristal?<\/b><\/i>\u00a0(<i>Who is Dayani Cristal?)<\/i>\u00a0\u00e8 un\u00a0docufilm\u00a0del\u00a02013\u00a0prodotto e interpretato da\u00a0Gael Garc\u00eda Bernal\u00a0per la regia d&#8217;esordio di\u00a0Marc Silver. \u00c8 stato presentato in anteprima mondiale al\u00a0Sundance Film Festivaldove ha vinto il premio per la miglior fotografia. Nel 2014 l&#8217;Amnesty International\u00a0lo ha eletto miglior documentario dell&#8217;anno.<\/p>\n<p>Il film affronta il tema dell&#8217;immigrazione negli Stati Uniti d&#8217;America\u00a0e si articola su due indagini: l&#8217;analisi del processo con cui normalmente si arriva all\u2019identificazione di un cadavere di un clandestino ritrovato nel deserto, e il racconto pi\u00f9 intimistico e diretto della pericolosa traversata dei\u00a0latinos, piena di sogni e di vite interrotte.<\/p>\n<p>Nell\u2019immenso deserto di Sonora, bruciato dal sole, la Polizia di Frontiera dell\u2019Arizona scopre il corpo di un uomo in decomposizione. Sotto una maglietta lacera, \u00e8 esposto un tatuaggio: Dayani Cristal.<\/p>\n<p>Chi \u00e8 quest\u2019uomo? Cosa lo ha portato qui? Come \u00e8 morto? Chi o cosa \u00e8 \u201cDayani Cristal\u201d?<\/p>\n<p>Seguendo un team di persone dell\u2019obitorio della Contea di Pima, in Arizona, il regista Marc Silver cerca di rispondere a queste domande, per dare a quest\u2019uomo un\u2019identit\u00e0.<\/p>\n<p>Mentre l\u2019indagine prosegue, l\u2019attore e attivista messicano Gael Garc\u00eda Bernal ripercorre i passi di quest\u2019uomo,\u00a0 lungo il sentiero dei migranti in America Centrale. Nel tentativo di capire cosa debba aver provato nel suo ultimo viaggio, si mescola ai migranti nella missione imminente per varcare il confine. Sperimenta, in prima persona i pericoli che sono costretti ad affrontare e impara dalle loro motivazioni, dalle loro speranze e dalle loro paure.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"&quot;Chi \u00e8 Dayani Cristal?&quot; luned\u00ec 15 gennaio alle 21.05 su Tv2000\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/HtA8pu-LJrI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"Luned\u00ec 18 giugno alle 22.50 su Tv2000 &#8211;\u00a0\u00a0Chi \u00e8 Dayani Cristal?\u00a0(Who is Dayani Cristal?)\u00a0\u00e8 un\u00a0docufilm\u00a0del\u00a02013\u00a0prodotto e interpretato da\u00a0Gael Garc\u00eda Bernal\u00a0per la regia d&#8217;esordio di\u00a0Marc Silver. \u00c8 stato presentato in anteprima mondiale al\u00a0Sundance Film Festivaldove ha vinto il premio per la miglior fotografia. Nel 2014 l&#8217;Amnesty International\u00a0lo ha eletto miglior documentario dell&#8217;anno. Il film affronta il [&hellip;]","protected":false},"author":35,"featured_media":4754,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/01\/Chi-\u00e8-Dayani-Cristal1-e1515597914472.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/4753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=4753"}],"version-history":[{"count":5,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/4753\/revisions"}],"predecessor-version":[{"id":5958,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/4753\/revisions\/5958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/4754"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=4753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=4753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=4753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}